{"id":350,"date":"2020-01-14T08:15:20","date_gmt":"2020-01-14T08:15:20","guid":{"rendered":"http:\/\/gearboxagricultural.com\/redsun-k-series-helical-bevel-gear-transmission-gearbox-for-agricultural-machinery\/"},"modified":"2020-07-08T03:45:39","modified_gmt":"2020-07-08T03:45:39","slug":"redsun-k-series-helical-bevel-gear-transmission-gearbox-for-agricultural-machinery","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/pt\/application\/redsun-k-series-helical-bevel-gear-transmission-gearbox-for-agricultural-machinery\/","title":{"rendered":"Redsun K series helical bevel gear transmission gearbox for agricultural machinery"},"content":{"rendered":"<p>\n<p>\n<p>Vis\u00e3o geral<\/p>\n<p>\n<p><p>Detalhes r\u00e1pidos<\/p>\n<dl>\n<dt>\n                    Local de origem:\n                <\/dt>\n<dd>\n<p>Zhejiang, China<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nome da marca:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Configura\u00e7\u00e3o da engrenagem:\n                <\/dt>\n<dd>\n<p>Bisel \/ Esquadria<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Torque de sa\u00edda:\n                <\/dt>\n<dd>\n<p>up to 52000Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidade de entrada:\n                <\/dt>\n<dd>\n<p>750-1500 rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidade de sa\u00edda:\n                <\/dt>\n<dd>\n<p>0.37~270rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Cor:\n                <\/dt>\n<dd>\n<p>personalizado<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacidade de fornecimento<\/p>\n<dl>\n<dt>\n                    Capacidade de fornecimento:\n                <\/dt>\n<dd>7000 Set\/Sets per   Month<\/dd>\n<\/dl>\n<\/p>\n<p><p>Embalagem e entrega<\/p>\n<dl>\n<dt>Detalhes da embalagem<\/dt>\n<dd>Standard export plywood case<\/dd>\n<\/dl>\n<dl>\n<dt>Porta<\/dt>\n<dd>NINGBO\/SHANGHAI PORT<\/dd>\n<\/dl>\n<dl>\n<dt>\n                        Tempo de espera<br \/>\n                        <i><\/i>:\n                    <\/dt>\n<dd>\n<table>\n<tr>\n<td>Quantidade (Conjuntos)<\/td>\n<td>1 &#8211; 1000<\/td>\n<td> &gt;1000<\/td>\n<\/tr>\n<tr>\n<td>Tempo estimado (dias)<\/td>\n<td>30<\/td>\n<td>A negociar.<\/td>\n<\/tr>\n<\/table>\n<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personaliza\u00e7\u00e3o online<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>Descri\u00e7\u00e3o do produto<\/p>\n<\/p>\n<p>\n<p><h3>Features<\/h3>\n<\/p>\n<p><p>&#9670; High modular design<br \/>&#9670; High loading support, stable transmitting and low noise level.<br \/>&#9670; Excellent sealing, wide range of industry application.<br \/>&#9670; High efficiency and save power.<br \/>&#9670; Save cost and low maintenance.<\/p>\n<\/p>\n<p>\n<h3>Main applied for<\/h3>\n<\/p>\n<p><p>&#9670; Harbor and shipping<br \/>&#9670; Hoist and transport<br \/>&#9670; Electric power<br \/>&#9670; Coal mining<br \/>&#9670; Cement and construction<br \/>&#9670; Paper and light industry<br \/>&#9670; Chemical industry and environmental protection<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Technical Data<\/p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>Material de constru\u00e7\u00e3o<\/p>\n<\/td>\n<td>\n<p>Cast iron\/Ductile iron<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Housing hardness<\/p>\n<\/td>\n<td>\n<p>HBS190-240<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Material da engrenagem<\/p>\n<\/td>\n<td>\n<p>20CrMnTi alloy steel<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Dureza superficial das engrenagens<\/p>\n<\/td>\n<td>\n<p>HRC58&deg;~62 &deg;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Gear core hardness<\/p>\n<\/td>\n<td>\n<p>HRC33~40<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Material do eixo de entrada\/sa\u00edda<\/p>\n<\/td>\n<td>\n<p>42CrMo alloy steel<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Input \/ Output shaft hardness<\/p>\n<\/td>\n<td>\n<p>HRC25~30<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Precis\u00e3o de usinagem de engrenagens<\/p>\n<\/td>\n<td>\n<p>accurate grinding, 6~5 Grade<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>\u00d3leo lubrificante<\/p>\n<\/td>\n<td>\n<p>GB L-CKC220-460, Shell Omala220-460<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Tratamento t\u00e9rmico<\/p>\n<\/td>\n<td>\n<p>tempering, cementiting, quenching, etc.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Efici\u00eancia<\/p>\n<\/td>\n<td>\n<p>94%~96% (depends on the transmission stage) <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Ru\u00eddo (M\u00c1XIMO)<\/p>\n<\/td>\n<td>\n<p>60~68dB<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Temp. rise  (MAX)<\/p>\n<\/td>\n<td>\n<p>40&deg;C <\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Aumento de temperatura (\u00f3leo) (m\u00e1x.)<\/p>\n<\/td>\n<td>\n<p>50&deg;C<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Vibra\u00e7\u00e3o<\/p>\n<\/td>\n<td>\n<p>\u226420\u00b5m<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Backlash<\/p>\n<\/td>\n<td>\n<p>&le;20Arcmin<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Marca de rolamentos<\/p>\n<\/td>\n<td>\n<p>China top brand bearing, HRB\/LYC\/ZWZ\/C&amp;U. Or other brands requested, SKF, FAG, INA, NSK.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Marca do retentor de \u00f3leo<\/p>\n<\/td>\n<td>\n<p>NAK &#8212; Taiwan or other brands requested<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><p>SIZE<\/p>\n<\/p>\n<\/td>\n<td colspan=\"2\">\n<p><p>Shaft Dia.(mm)<\/p>\n<p>Solid    Hallow<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Center Height<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Output Flange Dia.(mm)<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Power(kw)<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Raz\u00e3o<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Permissible Torque(N.m&#65289;<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>Weight(KGS)<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>37<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;25k6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;30h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>100<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;110\/160<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.18-3.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>5.36-106.38<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>200<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>11<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>47<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;30k6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;35h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>112<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;120\/200<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.18-3.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>5.81-131.87<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>400<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>20<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>57<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;35k6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;40h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>132<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;155\/250<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.18-5.5<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>6.57-145.14<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>600<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>27<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>67<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;40k6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;40h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>140<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;155\/250<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.18-5.5<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>7.14-144.79<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>820<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>33<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>77<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;50k6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;170<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>180<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;170\/300<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.37-11.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>7.24-292.18<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1550<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>57<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>87<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;60m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;60h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>212<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;215\/350<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>0.75-22.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>7.19-197.18<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>2700<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>85<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>97<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;70m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;70h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>265<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;260\/450<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1.1-30.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>8.95-176.05<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>4300<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>130<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>107<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;90m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;90h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>315<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;304\/450<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>3.0-45.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>8.74-141.46<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>8000<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>250<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>127<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;110m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;100h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>375<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;350\/550<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>7.5-90.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>8.68-146.07<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>13000<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>380<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>157<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;120m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>120h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>450<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;400\/660<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>11.0-160.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>12.65-150.41<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>18000<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>610<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>167<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;160m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>140h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>500<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;800<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>11.0-200.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>17.28-163.91<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>32000<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1015<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>187<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;190m6<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>160h7<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>600<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>&phi;800<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>18.5-200.0<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>17.27-180.78<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>50000<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1700<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Nossa empresa<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><h3>F\u00e1brica<\/h3>\n<\/p>\n<p>Nossa F\u00e1brica<\/p>\n<\/p>\n<p>\n<h3>Oficina<\/h3>\n<\/p>\n<p><p>Our Workshop<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><h3>Warehouse<\/h3>\n<\/p>\n<p><p>Our Warehouse<\/p>\n<\/p>\n<p>\n<h3>Team<\/h3>\n<\/p>\n<p><p>Nossa equipe<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Customer Photo<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p>Perguntas frequentes<\/p>\n<\/p>\n<p>\n<p><h3>P: Voc\u00eas s\u00e3o uma empresa comercial ou fabricante?<\/h3>\n<\/p>\n<p><p>A: N\u00f3s somos uma f\u00e1brica.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>P: Qual \u00e9 o prazo de entrega?<\/h3>\n<\/p>\n<p><p>A: Geralmente, s\u00e3o de 5 a 10 dias se os produtos estiverem em estoque, ou de 15 a 20 dias se n\u00e3o estiverem.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Q: Can we buy 1 pc of each item for quality testing?<\/h3>\n<\/p>\n<p><p>A: Sim, teremos prazer em aceitar um pedido experimental para teste de qualidade.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>P: Quais s\u00e3o as suas condi\u00e7\u00f5es de pagamento?<\/h3>\n<\/p>\n<p><p>A: Payment&lt;=1000USD, 100% in advance. Payment&gt;=1000USD, 30% T\/T in advance, balance before shippment.<br \/>If you have another question, pls feel free to contact us.<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Bevel \/ Miter Output Torque: up to 52000Nm Input Speed: 750-1500rpm Output Speed: 0.37~270rpm Color: customized Supply Ability Supply Ability: 7000 Set\/Sets per Month Packaging &amp; Delivery Packaging Details Standard export plywood case Port NINGBO\/SHANGHAI PORT Lead Time : Quantity(Sets) 1 &#8211; [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-350","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/posts\/350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/comments?post=350"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/posts\/350\/revisions"}],"predecessor-version":[{"id":2007,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/posts\/350\/revisions\/2007"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/media?parent=350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/categories?post=350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/pt\/wp-json\/wp\/v2\/tags?post=350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}