{"id":368,"date":"2020-01-14T08:15:36","date_gmt":"2020-01-14T08:15:36","guid":{"rendered":"http:\/\/gearboxagricultural.com\/agricultural-aerator-bevel-helical-gear-box-for-fish-farming-equipment\/"},"modified":"2020-07-08T03:45:37","modified_gmt":"2020-07-08T03:45:37","slug":"agricultural-aerator-bevel-helical-gear-box-for-fish-farming-equipment","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/it\/application\/agricultural-aerator-bevel-helical-gear-box-for-fish-farming-equipment\/","title":{"rendered":"Agricultural Aerator Bevel Helical Gear Box for fish farming equipment"},"content":{"rendered":"<p>\n<p>\n<p>Panoramica<\/p>\n<p>\n<p><p>Dettagli rapidi<\/p>\n<dl>\n<dt>\n                    Luogo di origine:\n                <\/dt>\n<dd>\n<p>Zhejiang, Cina<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nome del marchio:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Numero di modello:\n                <\/dt>\n<dd>\n<p>WKM80<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Potenza nominale:\n                <\/dt>\n<dd>\n<p>1~2HP<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Disposizione degli ingranaggi:\n                <\/dt>\n<dd>\n<p>Smusso \/ Mitra<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Coppia di uscita:\n                <\/dt>\n<dd>\n<p>~180Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocit\u00e0 di ingresso:\n                <\/dt>\n<dd>\n<p>1400\/1750rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocit\u00e0 di uscita:\n                <\/dt>\n<dd>\n<p>~125rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Materiale:\n                <\/dt>\n<dd>\n<p>FCD45 Housing<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Certificato:\n                <\/dt>\n<dd>\n<p>ISO9001<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Misurare:\n                <\/dt>\n<dd>\n<p>80<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Rapporto:\n                <\/dt>\n<dd>\n<p>1:14 ~ 1:17<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Input Type:\n                <\/dt>\n<dd>\n<p>Mounting Flange<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Output Type:\n                <\/dt>\n<dd>\n<p>Double Solid Output Shaft<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Garanzia:\n                <\/dt>\n<dd>\n<p>1 anno<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Colore:\n                <\/dt>\n<dd>\n<p>GREEN\/Customized<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Product Certificate:\n                <\/dt>\n<dd>\n<p>ISO9001<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Payment Term:\n                <\/dt>\n<dd>\n<p>Full payment before production<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacit\u00e0 di fornitura<\/p>\n<dl>\n<dt>\n                    Capacit\u00e0 di fornitura:\n                <\/dt>\n<dd>5000 Unit\/Units per   Month<\/dd>\n<\/dl>\n<\/p>\n<p><p>Imballaggio e consegna<\/p>\n<dl>\n<dt>Dettagli della confezione<\/dt>\n<dd>Cartone<\/dd>\n<\/dl>\n<dl>\n<dt>Porta<\/dt>\n<dd>KAOHSIUNG, TAIWAN<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personalizzazione online<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tDescrizione del prodotto \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<p><b>AERATOR BEVEL HELICAL GEAR BOX SPEED REDUCER<\/b><\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><p>Velocit\u00e0 di uscita<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>~125rpm<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>Velocit\u00e0 di ingresso<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1400\/1750rpm<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>Rated Power<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>1~2HP<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p>Coppia di uscita<\/p>\n<\/p>\n<\/td>\n<td>\n<p><p>~180Nm<\/p>\n<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<p><h3><b><br \/><\/b><\/h3>\n<h3><b>Specifica<\/b><\/h3>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>CHENTA<\/b>offre diverse serie di riduttori che consentono agli utenti di avere quelli pi\u00f9 adatti in tutti i diversi campi di applicazione. Per qualsiasi specifica oltre <b>CHENTA<\/b> standard, contattateci per ulteriori informazioni.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tProcesso di produzione \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>CHENTA<\/b>Dispone di una linea di produzione completa, dalla lavorazione dei componenti all'assemblaggio del cambio, fino all'ispezione e al collaudo. Tutti i prodotti sono sottoposti a rigorosi controlli di qualit\u00e0 prima dell'imballaggio e della spedizione.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tCertificazioni \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>CHENTA<\/b>\u00e8 un'azienda certificata ISO9001-2008 e registrata DUNS, con una serie di brevetti certificati dalle autorit\u00e0 negli Stati Uniti e a Taiwan.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tI nostri servizi \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>ODM:<\/b><br \/><b>CHENTA<\/b>Siamo specializzati nella personalizzazione di riduttori, inclusa la progettazione di alloggiamenti e ingranaggi secondo le specifiche del cliente. Possiamo fornire disegni 2D o 3D durante la fase di progettazione e vari test durante la verifica del prodotto, come ad esempio:<br \/>1. <u>Test di sviluppo<\/u>: Comunemente eseguito su materiali e moduli di ingranaggi, \u00e8 utile per determinare la fattibilit\u00e0 del progetto.<br \/>2. <u>Test del prototipo<\/u>: Il prototipo verr\u00e0 utilizzato per fornire un banco di prova con le stesse dimensioni e funzionalit\u00e0 del prodotto finale.<br \/>3. <u>Test di prova<\/u>: Il prototipo verr\u00e0 testato fino al fallimento per identificare potenziali problemi di garanzia e relativi costi.<br \/>4. <u>Test di accettazione<\/u>: A seconda della criticit\u00e0 dei guasti, i test possono essere condotti sulle unit\u00e0 di produzione iniziali e\/o sul campionamento AQL, oppure su ogni singola unit\u00e0 prodotta.<\/p>\n<p><b>OEM:<\/b><br \/>Sui prodotti progettati dal cliente,<b>CHENTA<\/b>Offriamo una gestione della produzione semplificata a prezzi competitivi. Offriamo valore aggiunto grazie alla qualit\u00e0 costante e all'ampia documentazione di rintracciabilit\u00e0. La flessibilit\u00e0 dei nostri programmi di produzione ci consente di migliorare i tempi di risposta. I test sopra menzionati sono disponibili in base alle specifiche del cliente.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tInformazioni aziendali \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Since the beginning of the company, our conviction is to &ldquo;<b>Raccogliere risorse umane eccellenti e ricercare e produrre prodotti di alta qualit\u00e0<\/b>&rdquo;. Our product policy is targeting at &ldquo;<b>Qualit\u00e0 garantita<\/b>&rdquo;, &ldquo;<b>Consegna puntuale<\/b>&rdquo;, &ldquo;<b>Prezzi competitivi<\/b>&rdquo;, &ldquo;<b>Produzione razionale<\/b>&rdquo;, and &ldquo;<b>Marketing internazionale<\/b>&rdquo;. With more than 50 years of experience in mechanical manufacturing and honest operation, a fine culture has naturally grown inside the corporation. This spirit is the most precious resource of our company. The motto of our company is based on &ldquo;<b>INNOVAZIONE<\/b>&rdquo;, &ldquo;<b>ONEST\u00c0<\/b>&rdquo;, &ldquo;<b>DILIGENZA<\/b>&rdquo;, and &ldquo;<b>EFFICIENZA<\/b>&rdquo;. Influenced gradually under such fine culture, all employees in <b>CHENTA<\/b> Lavorano sodo e si assumono responsabilit\u00e0. Cooperano tra loro e innovano attivamente. Con i loro sforzi, <b>CHENTA<\/b> continuare a svilupparsi e crescere per lottare per ottenere vantaggi reciproci.<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>RIDUTTORI CHENTA<\/b> ha svolto attivit\u00e0 di marketing a livello mondiale nei principali mercati di Taiwan, Asia e Nord America. A Taiwan, rimane ai vertici del settore e ha anche aperto filiali in America e Cina.<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tImballaggio e spedizione \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>CHENTA<\/b>offre vari metodi di imballaggio per soddisfare diverse esigenze e garantire che il prodotto non subisca danni prima di arrivare a destinazione.<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><b>CHENTA<\/b>I nostri team offrono un servizio professionale e tempestivo a tutte le richieste e garantiscono tutti i dettagli per soddisfare le esigenze del cliente in ogni transazione.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tProdotti correlati \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>\t\t\t\t\t\t\t\t\tFAQ \t\t\t\t\t\t\t<\/p>\n<\/p>\n<p>\n<p><b>1. Qual \u00e8 il MOQ?<\/b><br \/>Per il nostro modello standard, consultare le diverse pagine dei prodotti per verificare il MOQ. <br \/>Per i prodotti OEM\/ODM, contattateci per ulteriori informazioni.<\/p>\n<p><b>2. Quanto tempo ci vorr\u00e0 per la consegna?<\/b><br \/>Per il nostro modello standard, consultare le diverse pagine dei prodotti per verificare i tempi di consegna. <br \/>Per i prodotti OEM\/ODM, contattateci per ulteriori informazioni.<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Model Number: WKM80 Rated Power: 1~2HP Gearing Arrangement: Bevel \/ Miter Output Torque: ~180Nm Input Speed: 1400\/1750rpm Output Speed: ~125rpm Material: FCD45 Housing Certificate: ISO9001 Size: 80 Ratio: 1:14 ~ 1:17 Input Type: Mounting Flange Output Type: Double Solid Output Shaft Warranty: 1 Year [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-368","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":1989,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/368\/revisions\/1989"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}