{"id":300,"date":"2020-01-14T08:14:37","date_gmt":"2020-01-14T08:14:37","guid":{"rendered":"http:\/\/gearboxagricultural.com\/gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox\/"},"modified":"2020-07-08T03:45:43","modified_gmt":"2020-07-08T03:45:43","slug":"gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/it\/application\/gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox\/","title":{"rendered":"gearbox for agricultural machinery extruder ZLYJ extruder gearbox"},"content":{"rendered":"<p>\n<p>\n<p>Panoramica<\/p>\n<p>\n<p><p>Dettagli rapidi<\/p>\n<dl>\n<dt>\n                    Luogo di origine:\n                <\/dt>\n<dd>\n<p>Zhejiang, Cina<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nome del marchio:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Disposizione degli ingranaggi:\n                <\/dt>\n<dd>\n<p>Elicoidale<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Coppia di uscita:\n                <\/dt>\n<dd>\n<p>350~100000Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocit\u00e0 di ingresso:\n                <\/dt>\n<dd>\n<p>1500,1000,750rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocit\u00e0 di uscita:\n                <\/dt>\n<dd>\n<p>30-188r\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Certificato:\n                <\/dt>\n<dd>\n<p>ISO9001, CE, CCC<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Mounting position:\n                <\/dt>\n<dd>\n<p>Orizzontale (montato su piede) o verticale (montato su flangia)<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Colore:\n                <\/dt>\n<dd>\n<p>Secondo la richiesta del cliente<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Materiale:\n                <\/dt>\n<dd>\n<p>Acciaio o ghisa<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Materiale degli ingranaggi:\n                <\/dt>\n<dd>\n<p>Low carbon high alloy steel<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Gear accuracy:\n                <\/dt>\n<dd>\n<p>less than 6<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Qualit\u00e0:\n                <\/dt>\n<dd>\n<p>Super<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Progettazione dell'output:\n                <\/dt>\n<dd>\n<p>Solid shaft, hollow shaft, flange<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Trattamento termico:\n                <\/dt>\n<dd>\n<p>Carbocementazione\/tempra\/rettifica ingranaggi<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nome:\n                <\/dt>\n<dd>\n<p>plastic extruder reducer ZLYJ gearbox for concrete mixer extruder<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacit\u00e0 di fornitura<\/p>\n<dl>\n<dt>\n                    Capacit\u00e0 di fornitura:\n                <\/dt>\n<dd>500 Set\/Sets per   Week gearbox for extruder<\/dd>\n<\/dl>\n<\/p>\n<p><p>Imballaggio e consegna<\/p>\n<dl>\n<dt>Dettagli della confezione<\/dt>\n<dd>2, Imballaggio commerciale: sacchetto di plastica + scatola colorata + cartone + pallet di legno<br \/>\n<br \/>3, come richiesto dal cliente<br \/>\n<br \/>plastic extruder reducer ZLYJ gearbox for extruder&#8221;&gt;1, Industrial pakaging: Plastic tube+carton+wooden pallets<br \/>\n<br \/>2, Imballaggio commerciale: sacchetto di plastica + scatola colorata + cartone + pallet di legno<br \/>\n<br \/>3, come richiesto dal cliente<br \/>\n<br \/>plastic extruder reducer ZLYJ gearbox for extruder<\/dd>\n<\/dl>\n<dl>\n<dt>Porta<\/dt>\n<dd>Shanghai<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personalizzazione online<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p><strong> plastic extruder reducer ZLYJgearbox for concrete mixer extruder <\/strong><\/p>\n<\/p>\n<p><p>Descrizione del prodotto<\/p>\n<\/p>\n<p>plastic extruder reducer ZLYJ gearbox for concrete mixer extruder extrudinggearboxes<\/p>\n<p>Briefintroduction<\/p>\n<\/p>\n<table>\n<tbody>\n<tr align=\"left\">\n<td valign=\"center\">\n<\/td>\n<td valign=\"center\">\n<p>-ZLYJseriesreductiongearboxisatransmissionpart<\/p>\n<p>thatpossesseshighprecisionhardgearsurfaceand<\/p>\n<p>thrustblockdesignedforplasticscrewextruder.<\/p>\n<\/p>\n<p>-Thedesignofproductadaptsallkindsofnormspecified<\/p>\n<p>inZBJ19009-88\/itfeaturesthatgearandaxispartsare<\/p>\n<p>madeofhighstrengthalloysteel.<\/p>\n<\/p>\n<p>-Thegearisprocessesbycarburization,quenching<\/p>\n<p>andtoothgrindingprocess.<\/p>\n<\/p>\n<p>-Theprecisionofgearisgrade6specifiedinGB1009588.<\/p>\n<\/p>\n<p>-ThehardnessofgearsurfaceisHRC54~62.Atfrontend<\/p>\n<p>ofhollowinputaxisthereislargespecificationthrustbearing<\/p>\n<p>thatwillbearaxialthrustforcewhilethescrewis<\/p>\n<p>working.<\/p>\n<\/p>\n<p>-thecompletemachinefeaturescompact,highinbearing<\/p>\n<p>capacity,stableintransmission,lownoise,high<\/p>\n<p>efficiency,etc.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>ApplicationEnviroment:<\/p>\n<p>1.Theinputrotationofprimemovershallbe&le;1500rpm<\/p>\n<p>2.Theperipheralspeedofgeardriveshallbe&le;20m\/s<\/p>\n<p>3.Theworkingambienttemperatureshallbewithin-40~45&deg;C.Preheatthelubricationoiltoabove0&deg;C<\/p>\n<p>whentheambienttemperatureisbelow0&deg;C.Rotationisavailablebothforwardsandbackwards.<\/p>\n<p>However,thehighspeedshaftofsometypesofreducershasasinglewayoilpumpdirectingas<\/p>\n<p>defaultedtotheoutputshaftwhichrotatesclockwise.<\/p>\n<\/p>\n<p>FinishedProduct&amp;Application:<\/p>\n<p>ThisZLYJgearboxaremainlyusedinPlasticExtrudingMachine,likeEPS,PE&#8230;.<\/p>\n<\/p>\n<p>Processingequipment:<\/p>\n<p>WehaveNilescontourgeargrindingmachineimportedfromGermany,OKUMAhorizontalmachiningcenter<\/p>\n<p>importedfromJapan,gearinspectionandtestcenterandthree-coordinatesmeasuringmachine.<\/p>\n<\/p>\n<p><p>Imballaggio e spedizione<\/p>\n<\/p>\n<p><strong> plastic extruder reducer ZLYJ twin screw extruder gearbox <\/strong><\/p>\n<p><strong>1, Imballaggio industriale: tubo di plastica + cartone + pallet di legno<\/strong><br \/><strong>2, Imballaggio commerciale: sacchetto di plastica + scatola colorata + cartone + pallet di legno<\/strong><br \/><strong>3, Come requisito del cliente <\/strong><\/p>\n<p><strong>4, Spedizione: via mare, via aerea, tramite DHL Fedex UPS ecc.<\/strong><\/p>\n<\/p>\n<\/p>\n<p><p>Informazioni aziendali<\/p>\n<\/p>\n<p>In qualit\u00e0 di produttore leader di motori industriali, riduttori di velocit\u00e0, azionamenti ecc. in Cina, la nostra azienda ha sempre aderito al concetto di \"innovazione tecnologica leader, raggiungimento di una qualit\u00e0 eccellente\". I prodotti principali sono: micro motoriduttori, motoriduttori di medie dimensioni, motori con regolazione della velocit\u00e0 del freno, motori di coppia, motori CC, motore a vite senza fine NMRV, motoriduttori conici elicoidali, riduttore a vite senza fine serie WP RV, riduttori elicoidali a denti rigidi, riduttori a vite senza fine elicoidali, riduttori elicoidali ad alberi paralleli, riduttori conici a spirale, martinetti a vite senza fine SWL e JW, riduttori conici a denti rigidi, riduttori epicicloidali ecc. Prodotti di trasmissione, ampiamente utilizzati in varie linee di produzione industriale, come macchinari per il trasporto, macchinari alimentari, macchinari medicali, macchinari per la stampa, macchinari tessili, macchinari per l'imballaggio, apparecchiature per ufficio, strumentazione e altri settori, sono i prodotti di supporto preferiti per le apparecchiature di automazione.<\/p>\n<\/p>\n<p><strong>PERCH\u00c9 SCEGLIERCI?<\/strong><br \/> -SERVIZIO ECCELLENTE, BASSI COSTI, ELEVATA STABILIT\u00c0, QUALIT\u00c0 AVANZATA, FORZA LAVORO STABILE<br \/> - Possediamo circa 300 set di apparecchiature di lavorazione e di collaudo per garantire elevata precisione e qualit\u00e0, come la rettificatrice per ingranaggi di precisione REISHAUER (Svizzera), la dentatrice per ingranaggi PFAUTER (Germania), la fresatrice per ingranaggi conici Gleason, la macchina di misura a tre coordinate, ecc.<\/p>\n<\/p>\n<p><p>I nostri servizi<\/p>\n<\/p>\n<ul>\n<li>Consegna puntuale<\/li>\n<li>servizio 24 ore su 24<\/li>\n<li>Qualit\u00e0 garantita<\/li>\n<li>Supporto alla visita in fabbrica<\/li>\n<li>Supporti tecnologici<\/li>\n<\/ul>\n<p>Il team di Shanghai Taiqi accoglie con favore la vostra richiesta e collaborazione.<\/p>\n<ul>\n<li>La vostra visita ci \u00e8 stata molto gradita!<\/li>\n<\/ul>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Helical Output Torque: 350~100000Nm Input Speed: 1500,1000,750rpm Output Speed: 30-188r\/min Certificate: ISO9001, CE, CCC Mounting position: Horizontal (foot mounted) or Vertical (flange mounted) Color: According to customer&#039;s request Material: Steel or cast iron Gear material: Low carbon high alloy steel Gear accuracy: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-300","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/300\/revisions"}],"predecessor-version":[{"id":2058,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/posts\/300\/revisions\/2058"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/media?parent=300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/categories?post=300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/it\/wp-json\/wp\/v2\/tags?post=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}