{"id":341,"date":"2020-01-14T08:15:12","date_gmt":"2020-01-14T08:15:12","guid":{"rendered":"http:\/\/gearboxagricultural.com\/custom-agricultural-110-transmission-gearbox-with-differential\/"},"modified":"2020-07-08T03:45:40","modified_gmt":"2020-07-08T03:45:40","slug":"boite-de-vitesses-agricole-personnalisee-110-avec-differentiel","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/fr_fr\/application\/boite-de-vitesses-agricole-personnalisee-110-avec-differentiel\/","title":{"rendered":"Bo\u00eete de vitesses agricole personnalis\u00e9e 110 avec diff\u00e9rentiel"},"content":{"rendered":"<p>\n<p>\n<p>Aper\u00e7u<\/p>\n<p>\n<p><p>D\u00e9tails rapides<\/p>\n<dl>\n<dt>\n                    Lieu d'origine :\n                <\/dt>\n<dd>\n<p>Zhejiang, Chine<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom de marque :\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Agencement des engrenages :\n                <\/dt>\n<dd>\n<p>Plan\u00e9taire<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Couple de sortie\u00a0:\n                <\/dt>\n<dd>\n<p>JUSQU'\u00c0 2320<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>1400 tr\/min ou autre<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse de sortie :\n                <\/dt>\n<dd>\n<p>7.5,10,15,20,30,40,50,60<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Secteurs d'activit\u00e9 concern\u00e9s\u00a0:\n                <\/dt>\n<dd>\n<p>Magasins de mat\u00e9riaux de construction, usines de fabrication, ateliers de r\u00e9paration de machines, usines agroalimentaires, exploitations agricoles, restaurants, usage domestique, commerce de d\u00e9tail, magasins d'alimentation, imprimeries, travaux de construction, \u00e9nergie et mines<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom du produit :\n                <\/dt>\n<dd>\n<p>NW<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Garantie:\n                <\/dt>\n<dd>\n<p>1 an<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Mat\u00e9riau du bo\u00eetier :\n                <\/dt>\n<dd>\n<p>fonderie d'aluminium et de fer<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Commande minimale\u00a0:\n                <\/dt>\n<dd>\n<p>Les commandes d'\u00e9chantillons sont accept\u00e9es.<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Personnalisation\u00a0:\n                <\/dt>\n<dd>\n<p>accepter<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Inspection :\n                <\/dt>\n<dd>\n<p>Pr\u00e9cision<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Port de chargement :\n                <\/dt>\n<dd>\n<p>Ningbo ou Shanghai<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    D\u00e9lai de livraison:\n                <\/dt>\n<dd>\n<p>en 15 jours ouvrables<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Couleur:\n                <\/dt>\n<dd>\n<p>bleu ou gary selon la demande<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Formulaire de sortie\u00a0:\n                <\/dt>\n<dd>\n<p>Arbre plein ou creux, sortie \u00e0 bride<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacit\u00e9 d'approvisionnement<\/p>\n<dl>\n<dt>\n                    Capacit\u00e9 d'approvisionnement :\n                <\/dt>\n<dd>10\u00a0000 pi\u00e8ces par mois<\/dd>\n<\/dl>\n<\/p>\n<p><p>Emballage et livraison<\/p>\n<dl>\n<dt>D\u00e9tails de l'emballage<\/dt>\n<dd>1) Emballage int\u00e9rieur : papier huil\u00e9, sac en poly\u00e9thyl\u00e8ne, bo\u00eete.<br \/>\n<br \/>2) Emballage ext\u00e9rieur : Caisse en bois ou palette.<br \/>\n<br \/>3) Un emballage personnalis\u00e9 est \u00e9galement disponible. &gt; Bo\u00eete de vitesses agricole personnalis\u00e9e 110 avec diff\u00e9rentiel<br \/>\n<br \/>1) Emballage int\u00e9rieur : papier huil\u00e9, sac en poly\u00e9thyl\u00e8ne, bo\u00eete.<br \/>\n<br \/>2) Emballage ext\u00e9rieur : Caisse en bois ou palette.<br \/>\n<br \/>3) Un emballage personnalis\u00e9 est \u00e9galement disponible.<\/dd>\n<\/dl>\n<dl>\n<dt>Port<\/dt>\n<dd>Ningbo ou Shanghai<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personnalisation en ligne<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<h2>Bo\u00eete de vitesses agricole personnalis\u00e9e 110 avec diff\u00e9rentiel<\/h2>\n<h2>Pr\u00e9sentation du produit<\/h2>\n<\/p>\n<\/p>\n<h2>Quelles sont les sp\u00e9cifications de nos produits ?<\/h2>\n<\/p>\n<p><p>Description du produit<\/p>\n<\/p>\n<table>\n<tbody>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Taper<\/p>\n<\/td>\n<td valign=\"center\">\n<p>r\u00e9ducteur plan\u00e9taire<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Mod\u00e8le<\/p>\n<\/td>\n<td valign=\"center\">\n<p>NW<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Rapport<\/p>\n<\/td>\n<td valign=\"center\">\n<p>7.5,10,15,20,25,30,40,50,60,80,100.<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Couleur<\/p>\n<\/td>\n<td valign=\"center\">\n<p>Bleu\/gris argent\u00e9 ou sur demande du client<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td rowspan=\"4\" valign=\"center\">\n<p>Mat\u00e9riel<\/p>\n<\/td>\n<td valign=\"center\">\n<p>alliage d'aluminium<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Roue \u00e0 vis sans fin : Bronze d'aluminium ou Bronze de zinc<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Arbre \u00e0 vis sans fin : 20CrMnTi<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Arbre de sortie : acier-45#<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Emballage<\/p>\n<\/td>\n<td valign=\"center\">\n<p>Carton, carton alv\u00e9ol\u00e9, caisse en bois avec palette en bois<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Garantie<\/p>\n<\/td>\n<td valign=\"center\">\n<p>1 an<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Puissance d'entr\u00e9e<\/p>\n<\/td>\n<td valign=\"center\">\n<p>0,09 kW, 0,18 kW, 1,1 kW, 1,5 kW, 2,2 kW, 3 kW, 4 kW, 5,5 kW, 7,5 kW, 11 kW bient\u00f4t.<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Utilisations<\/p>\n<\/td>\n<td valign=\"center\">\n<p>Machines industrielles : Agroalimentaire, C\u00e9ramique, Chimie, Emballage, Teinture, Travail du bois, Verre.<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Bride<\/p>\n<\/td>\n<td valign=\"center\">\n<p>bride standard ou sur demande du client<\/p>\n<\/td>\n<\/tr>\n<tr align=\"left\">\n<td valign=\"center\">\n<p>Lubrifiant<\/p>\n<\/td>\n<td valign=\"center\">\n<p>huile synth\u00e9tique ou huile pour engrenages \u00e0 vis sans fin<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Envoyer une demande &gt;&gt;&gt;<\/strong><\/p>\n<\/p>\n<h2>Quels autres produits ?<\/h2>\n<p><p>Plus de produits<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p><strong>Envoyez-nous votre dessin ou \u00e9chantillon d\u00e8s maintenant &gt;&gt;&gt;<\/strong><\/p>\n<\/p>\n<h2>\u00c0 propos de nous<\/h2>\n<\/p>\n<\/p>\n<\/p>\n<p><strong>Envoyez-nous votre dessin ou \u00e9chantillon d\u00e8s maintenant &gt;&gt;&gt;<\/strong><\/p>\n<\/p>\n<h2>Quels sont les commentaires de nos clients ?<\/h2>\n<p><p>Commentaires des clients<\/p>\n<\/p>\n<\/p>\n<h2>Pourquoi nous choisir ?<\/h2>\n<p><strong>1) Plus de 22 ans d'exp\u00e9rience en usine dans le domaine des engrenages<\/strong><br \/><strong>2) Nous disposons d'une main-d'\u0153uvre exp\u00e9riment\u00e9e et qualifi\u00e9e ainsi que d'une \u00e9quipe de contr\u00f4le qualit\u00e9.<\/strong><br \/><strong>3) Notre usine est situ\u00e9e pr\u00e8s des ports de Ningbo et de Shanghai.<\/strong><br \/><strong>4) \u00c9quipe marketing professionnelle pour la conception et la r\u00e9alisation d'\u00e9chantillons pour les clients<\/strong><br \/><strong>5) Offrir un service de r\u00e9ponse rapide et un devis professionnel dans les meilleurs d\u00e9lais<\/strong><\/p>\n<\/p>\n<p><strong>Envoyez-nous vos dessins ou \u00e9chantillons d\u00e8s maintenant &gt;&gt;&gt;<\/strong><\/p>\n<\/p>\n<h2>Emballage et exp\u00e9dition<\/h2>\n<\/p>\n<h2>Certification<\/h2>\n<\/p>\n<h2>Qu'est-ce qui le diff\u00e9rencie des autres ?<\/h2>\n<\/p>\n<p><strong>Envoyer une demande ici &gt;&gt;&gt;<\/strong><\/p>\n<h2>D'autres questions ?<\/h2>\n<p><p>FAQ<\/p>\n<\/p>\n<p><strong>Q : Quel est le d\u00e9lai de livraison habituel ?<\/strong><br \/>R: Normalement 10 \u00e0 25 jours apr\u00e8s confirmation de la commande.<\/p>\n<p><strong>Q : Quelle est la garantie de la qualit\u00e9 du produit ?<\/strong><br \/>A : Nous disposons d'une main-d'\u0153uvre exp\u00e9riment\u00e9e et qualifi\u00e9e, ainsi que d'une \u00e9quipe de contr\u00f4le qualit\u00e9. N'ayez aucune inqui\u00e9tude.<\/p>\n<p><strong>Q : Quel est le mode de paiement ?<\/strong><br \/>A: Nous acceptons les paiements par virement bancaire (T\/T), lettre de cr\u00e9dit (L\/C), PayPal, Western Union et la garantie commerciale Alibaba.<\/p>\n<p> <strong>Q : Quand puis-je obtenir le devis pour ma demande ?<\/strong><br \/> A: En g\u00e9n\u00e9ral, le devis vous sera envoy\u00e9 sous un jour ouvr\u00e9 une fois que tous les d\u00e9tails concernant les produits seront clairs. En cas d'urgence, nous pouvons vous \u00e9tablir un devis sous deux heures sur la base des informations que vous nous fournirez.<\/p>\n<p><strong>Q : Quel est le d\u00e9lai de production en s\u00e9rie ?<\/strong><br \/>A : Normalement 15 jours. Commande urgente possible.<\/p>\n<p> <strong>Q : Puis-je obtenir un \u00e9chantillon avant la production en s\u00e9rie ?<\/strong><br \/> A : Bien s\u00fbr ! Le processus de production habituel pr\u00e9voit la r\u00e9alisation d'un \u00e9chantillon de pr\u00e9-production pour votre \u00e9valuation de la qualit\u00e9. La production en s\u00e9rie d\u00e9butera apr\u00e8s votre confirmation de cet \u00e9chantillon.<\/p>\n<p><strong>Q : Les frais d'\u00e9chantillon sont-ils remboursables ?<\/strong><br \/>R : Oui, normalement les frais d'\u00e9chantillon sont remboursables lorsque vous confirmez la production en s\u00e9rie, mais pour toute situation particuli\u00e8re, veuillez contacter les personnes qui suivent votre commande.<\/p>\n<p><strong>Q : Quel est le MOQ ?<\/strong><br \/> A: Normalement 100 pi\u00e8ces.<\/p>\n<\/p>\n<p><strong>Envoyer une demande ici &gt;&gt;&gt;<\/strong><\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Planetary Output Torque: UP TO 2320 Input Speed: 1400rpm or other Output Speed: 7.5,10,15,20,30,40,50,60 Applicable Industries: Building Material Shops, Manufacturing Plant, Machinery Repair Shops, Food &amp; Beverage Factory, Farms, Restaurant, Home Use, Retail, Food Shop, Printing Shops, Construction works, Energy &amp; Mining [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-341","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"predecessor-version":[{"id":2016,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/341\/revisions\/2016"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}