{"id":307,"date":"2020-01-14T08:14:43","date_gmt":"2020-01-14T08:14:43","guid":{"rendered":"http:\/\/gearboxagricultural.com\/factor-supply-speed-increasing-planetary-gearbox-t-bevel-gear-box-reducer-for-agricultural-machinery\/"},"modified":"2020-07-08T03:45:42","modified_gmt":"2020-07-08T03:45:42","slug":"factor-supply-speed-increasing-planetary-gearbox-t-bevel-gear-box-reducer-for-agricultural-machinery","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/fr_fr\/application\/factor-supply-speed-increasing-planetary-gearbox-t-bevel-gear-box-reducer-for-agricultural-machinery\/","title":{"rendered":"Factor supply speed increasing planetary gearbox T bevel gear box reducer for agricultural machinery"},"content":{"rendered":"<p>\n<p>\n<p>Aper\u00e7u<\/p>\n<p>\n<p><p>D\u00e9tails rapides<\/p>\n<dl>\n<dt>\n                    Lieu d'origine :\n                <\/dt>\n<dd>\n<p>Zhejiang, Chine<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom de marque :\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Agencement des engrenages :\n                <\/dt>\n<dd>\n<p>Biseau \/ Onglet<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Couple de sortie\u00a0:\n                <\/dt>\n<dd>\n<p>130-550 N.m, 130-550 N.m<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>10-1500 tr\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse de sortie :\n                <\/dt>\n<dd>\n<p>10-1500 tr\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Secteurs d'activit\u00e9 concern\u00e9s\u00a0:\n                <\/dt>\n<dd>\n<p>Magasins de mat\u00e9riaux de construction, ateliers de r\u00e9paration de machines, exploitations agricoles, \u00e9nergie et mines<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom du produit :\n                <\/dt>\n<dd>\n<p>dispositif de direction \u00e0 engrenages coniques h\u00e9lico\u00efdaux s\u00e9rie T<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Rapport:\n                <\/dt>\n<dd>\n<p>1,1.5,2,2.5,3,4,5<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Num\u00e9ro de mod\u00e8le :\n                <\/dt>\n<dd>\n<p>T2, T4, T6, T7, T8, T10, T12, T16, T20, T25<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Certificat:\n                <\/dt>\n<dd>\n<p>ISO9001<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Position de montage :\n                <\/dt>\n<dd>\n<p>Montage sur arbre<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Formulaire de saisie\u00a0:\n                <\/dt>\n<dd>\n<p>arbres d'entr\u00e9e<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Puissance d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>0,015-400 kW<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>10-1500 tr\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Mat\u00e9riau du palier :\n                <\/dt>\n<dd>\n<p>C&amp;U, NSK, SKF ou sur demande du client<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Emballage et livraison<\/h3>\n<dl>\n<dt>Unit\u00e9s de vente :<\/dt>\n<dd>Article unique<\/dd>\n<\/dl>\n<dl>\n<dt>Taille de l'emballage individuel\u00a0:<\/dt>\n<dd>\n                                            42 x 42 x 15,2 cm\n                                    <\/dd>\n<\/dl>\n<dl>\n<dt>Poids brut unitaire :<\/dt>\n<dd>21,0 kg<\/dd>\n<\/dl>\n<dl>\n<dt>\n                D\u00e9lai de mise en \u0153uvre<br \/>\n                <i><\/i>:\n                <\/dt>\n<dd>\n<table>\n<tr>\n<td>Quantit\u00e9 (pi\u00e8ces)<\/td>\n<td>1 &#8211; 1<\/td>\n<td>2 &#8211; 5<\/td>\n<td>\n                        &gt;5<\/td>\n<\/tr>\n<tr>\n<td>Dur\u00e9e estim\u00e9e (jours)<\/td>\n<td>3<\/td>\n<td>10<\/td>\n<td>\u00c0 n\u00e9gocier<\/td>\n<\/tr>\n<\/table>\n<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personnalisation en ligne<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>Description du produit<\/p>\n<\/p>\n<p>\n<p><h3><b>Dispositif de direction \u00e0 engrenages coniques h\u00e9lico\u00efdaux s\u00e9rie T<\/b><br \/><\/h3>\n<\/p>\n<p><p>1. Les d\u00e9flecteurs \u00e0 chanfrein spiral de la s\u00e9rie T, disponibles en diff\u00e9rents types, sont standardis\u00e9s. Tous les rapports 1:1, 1,5:1, 2:1, 2,5:1, 3:1, 4:1 et 5:1 sont r\u00e9els. L'efficacit\u00e9 moyenne est de 98%.<\/p>\n<p>2. Il existe un arbre d'entr\u00e9e, deux arbres d'entr\u00e9e, un arbre de sortie unilat\u00e9ral et un arbre de sortie bilat\u00e9ral.<\/p>\n<p>3. L'engrenage conique spiral\u00e9 peut tourner dans les deux sens et transmettre en douceur, faible bruit, vibrations l\u00e9g\u00e8res, hautes performances.<\/p>\n<p>4. Si le rapport n'est pas de 1:1, si la vitesse d'entr\u00e9e sur un arbre extensible unique, la vitesse de sortie sera r\u00e9duite ;<\/p>\n<p>    si la vitesse d'entr\u00e9e sur l'arbre \u00e0 double extension est r\u00e9duite, la vitesse de sortie le sera \u00e9galement.<\/p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><h3><b>Caract\u00e9ristiques du collecteur \u00e0 engrenages coniques h\u00e9lico\u00efdaux\u00a0:<br \/><\/b><br \/><\/h3>\n<\/p>\n<p><p>\u25cf Coque : Moul\u00e9e en fonte FC-25 \u00e0 haute teneur en acier ;<\/p>\n<p>\u25cf Engrenage : Il est fabriqu\u00e9 en acier alli\u00e9 de haute qualit\u00e9 et de haute puret\u00e9 50CrMnT tremp\u00e9 et revenu par c\u00e9mentation, trempe et rectification.<\/p>\n<p>\u25cf Broche : Acier alli\u00e9 40Cr de haute qualit\u00e9 et de haute puret\u00e9, trait\u00e9 par trempe et revenu, avec une capacit\u00e9 de charge de suspension \u00e9lev\u00e9e.<\/p>\n<p>\u25cfRoulements\u00a0: Roulements \u00e0 rouleaux coniques \u00e0 capacit\u00e9 de charge \u00e9lev\u00e9e\u00a0;<\/p>\n<p>\u25cf Joint d'huile : Joint d'huile \u00e0 double l\u00e8vre import\u00e9, avec une tr\u00e8s haute capacit\u00e9 de pr\u00e9vention des fuites de poussi\u00e8re et d'huile.<\/p>\n<\/p>\n<p>\n<p><b>Facteur de service f1<\/b><\/p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td rowspan=\"2\">\n<p><p><b><br \/><\/b><\/p>\n<p><b>Caract\u00e9ristique de charge<\/b><\/p>\n<\/p>\n<\/td>\n<td colspan=\"3\">\n<p><p><b>Heures de fonctionnement\/jour (heure)<\/b><\/p>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>\u22642<\/p>\n<\/td>\n<td>\n<p>2~10<\/p>\n<\/td>\n<td>\n<p>0~24<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p><b>COMME<\/b><\/p>\n<\/p>\n<\/td>\n<td>\n<p>1.00(1.00)<\/p>\n<\/td>\n<td>\n<p>1.00(1.25)<\/p>\n<\/td>\n<td>\n<p>1.25(1.50)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p><b>Uniforme<\/b><\/p>\n<\/p>\n<\/td>\n<td>\n<p>Adapt\u00e9 pour l'accouplement moteur<\/p>\n<\/td>\n<td>\n<p>80B5<\/p>\n<\/td>\n<td>\n<p>installation de montage de moteur<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><p><b>0,75 kW<\/b><\/p>\n<\/p>\n<\/td>\n<td>\n<p>puissance du moteur \u00e9lectrique<\/p>\n<\/td>\n<td>\n<p>B3<\/p>\n<\/td>\n<td>\n<p>Position de montage<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>\n<h3>ARBRE DE SORTIE DE HAUTE QUALIT\u00c9<\/h3>\n<\/p>\n<p><p>Nouvel essieu standard, usinage de haute pr\u00e9cision, soumis \u00e0 des tests rigoureux d'\u00e9quilibrage dynamique et statique, pour garantir un fonctionnement silencieux et fluide du r\u00e9ducteur.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>MAT\u00c9RIAU DE COQUE DE HAUTE QUALIT\u00c9<\/h3>\n<\/p>\n<p><p>Le corps de la bo\u00eete est fabriqu\u00e9 en mat\u00e9riau HT200, nettoy\u00e9 par un \u00e9quipement professionnel de tamisage et de lavage afin de garantir que la cavit\u00e9 int\u00e9rieure du corps de la bo\u00eete soit plus propre et exempte de limaille de fer.<\/p>\n<p><\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<h3>MAT\u00c9RIAU DE COQUE DE HAUTE QUALIT\u00c9<\/h3>\n<\/p>\n<p><p>Mat\u00e9riau 20CrMnTi \u2013 acier alli\u00e9 \u00e0 faible teneur en carbone<\/p>\n<p>Usinage par rectifieuse d'engrenages import\u00e9e, duret\u00e9 \u00e9lev\u00e9e, performances stables.<\/p>\n<p>Traitement thermique de c\u00e9mentation sous vide, couche de c\u00e9mentation uniforme.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><b>Dimensions de montage du dispositif de direction \u00e0 engrenages coniques spiral\u00e9s s\u00e9rie T<\/b><\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Notre entreprise<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><h3>JIANGSU DEVO GEAR TECHNOLOGY CO., LTD<\/h3>\n<\/p>\n<p><p>Notre entreprise est situ\u00e9e dans la ville de Xuzhou, province du Jiangsu, en Chine. <\/p>\n<p>Nous commercialisons des produits de transmission de puissance, notamment des r\u00e9ducteurs de vitesse, des bo\u00eetes de vitesses, des moteurs \u00e9lectriques associ\u00e9s et d'autres accessoires de transmission de puissance. Gr\u00e2ce \u00e0 leur polyvalence, nos produits trouvent des applications dans de nombreux secteurs\u00a0: stations d'\u00e9puration, dragage, industrie chimique, grues, aci\u00e9ries, convoyeurs, industrie papeti\u00e8re, industrie cimenti\u00e8re, t\u00e9l\u00e9ph\u00e9riques, etc. Reconnus pour leur excellente qualit\u00e9 et leur prix comp\u00e9titif, nos produits jouissent d'une excellente r\u00e9putation aupr\u00e8s de nos clients et de nos pairs du monde entier. <\/p>\n<p>De plus, les investissements en R&amp;D augmentent chaque ann\u00e9e afin de mieux r\u00e9pondre aux nouvelles exigences de nos clients et de nous adapter aux nouvelles tendances du secteur.<br \/>Dans le respect des principes d'honn\u00eatet\u00e9 et d'int\u00e9r\u00eat mutuel, nous esp\u00e9rons sinc\u00e8rement coop\u00e9rer avec vous.<\/p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p>Domaine d'application<\/p>\n<\/p>\n<p>\n<p>Les engrenages coniques \u00e0 denture spirale de la s\u00e9rie T sont largement utilis\u00e9s dans les machines alimentaires, les machines chimiques, les machines \u00e0 bois, les machines pharmaceutiques, les machines agricoles, les \u00e9quipements textiles, les \u00e9quipements de fusion, les \u00e9quipements m\u00e9dicaux et autres produits n\u00e9cessitant une transmission par d\u00e9c\u00e9l\u00e9ration.<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Emballage et transport<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><h3>EMBALLAGE ET TRANSPORT<\/h3>\n<\/p>\n<p><p>&#9679;<b>Emballage : I<\/b>Afin de garantir l'int\u00e9grit\u00e9 de l'aspect du produit, nous choisirons des cartons, des palettes en bois et des conteneurs en fonction des besoins du client.<\/p>\n<p>&#9679;<b>D\u00e9lai de livraison:<\/b> Chaque r\u00e9ducteur est fabriqu\u00e9 et test\u00e9 selon des proc\u00e9dures strictes et fixes afin de garantir sa qualit\u00e9 avant sa sortie d'usine et sa livraison dans les d\u00e9lais.<\/p>\n<p>&#9679;<b>Mode de transport : <\/b>Nous choisirons le mode de transport le plus adapt\u00e9 \u00e0 nos clients en fonction du poids et des dimensions des marchandises. Nous pouvons \u00e9galement choisir le mode de transport selon leurs besoins.<\/p>\n<p>&#9679;<b>R\u00e9ception et service apr\u00e8s-vente\u00a0:<\/b> Apr\u00e8s r\u00e9ception de la marchandise, veuillez v\u00e9rifier son \u00e9tat. Nous assurons un service apr\u00e8s-vente irr\u00e9prochable.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>FAQ<\/p>\n<\/p>\n<p>\n<p><b><i>Q1 : \u00cates-vous une soci\u00e9t\u00e9 commerciale ou une <\/i>fabricant<i> ?<br \/><\/i><\/b>A: Nous sommes un fabricant situ\u00e9 dans la province du Jiangsu, en Chine. Notre entreprise poss\u00e8de des comp\u00e9tences en mati\u00e8re de fabrication, de transformation, de conception et de recherche et d\u00e9veloppement. Nous serions ravis de vous accueillir.<\/p>\n<p><b>Q2 : Comment s\u00e9lectionnons-nous les mod\u00e8les et les sp\u00e9cifications ?<br \/><\/b>A: En fonction des d\u00e9tails sp\u00e9cifiques des exigences figurant dans la demande, nous recommanderons les mod\u00e8les de produits en synth\u00e9tisant les facteurs suivants\u00a0: domaine d\u2019utilisation des produits, puissance, bras de couple et rapport\u2026<\/p>\n<p><b>Q3\u00a0: Quel est votre prix\u00a0? Pouvez-vous offrir une r\u00e9duction\u00a0?<br \/><\/b>A: Nos prix sont toujours comp\u00e9titifs. Si le client passe une commande importante, nous lui accorderons bien s\u00fbr une r\u00e9duction.<\/p>\n<p><b>Q4 : Combien de temps dois-je attendre pour obtenir une r\u00e9ponse apr\u00e8s avoir envoy\u00e9 ma demande ?<br \/><\/b>A4 : Nous vous r\u00e9pondrons d\u00e8s que possible, dans un d\u00e9lai maximum de 12 heures.<\/p>\n<p><b>Q5 : Quelle est la p\u00e9riode de garantie de votre produit ?<br \/><\/b>A: Nous poss\u00e9dons les certifications ISO9001, CE et SGS.<\/p>\n<p><b>Q6 : Dans quels secteurs vos r\u00e9ducteurs sont-ils utilis\u00e9s ?<br \/><\/b>A: Nos r\u00e9ducteurs sont largement utilis\u00e9s dans les \u00e9quipements m\u00e9tallurgiques, les \u00e9quipements miniers, les \u00e9quipements d'automatisation, les machines alimentaires, les \u00e9quipements d'emballage, les \u00e9quipements pour l'industrie du tabac, etc.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Notre service<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Produits associ\u00e9s<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Bevel \/ Miter Output Torque: 130-550N.m, 130-550N.m Input Speed: 10-1500 r\/min Output Speed: 10-1500r\/min Applicable Industries: Building Material Shops, Machinery Repair Shops, Farms, Energy &amp; Mining Product name: T series spiral bevel gear steering device Ratio: 1,1.5,2,2.5,3,4,5 Model number: T2,T4,T6,T7,T8,T10,T12,T16,T20,T25 Certificate: ISO9001 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-307","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=307"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/307\/revisions"}],"predecessor-version":[{"id":2050,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/307\/revisions\/2050"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}