{"id":286,"date":"2020-01-14T08:14:24","date_gmt":"2020-01-14T08:14:24","guid":{"rendered":"http:\/\/gearboxagricultural.com\/t-series-90-degree-helical-cone-bevel-agricultural-gearbox-2\/"},"modified":"2020-07-08T03:45:44","modified_gmt":"2020-07-08T03:45:44","slug":"reducteur-agricole-a-engrenages-coniques-helicoidaux-a-90-degres-serie-t-2","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/fr_fr\/application\/reducteur-agricole-a-engrenages-coniques-helicoidaux-a-90-degres-serie-t-2\/","title":{"rendered":"Bo\u00eete de vitesses agricole \u00e0 engrenages coniques h\u00e9lico\u00efdaux \u00e0 90 degr\u00e9s s\u00e9rie T"},"content":{"rendered":"<p>\n<p>\n<p>Aper\u00e7u<\/p>\n<p>\n<p><p>D\u00e9tails rapides<\/p>\n<dl>\n<dt>\n                    Lieu d'origine :\n                <\/dt>\n<dd>\n<p>Zhejiang, Chine<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom de marque :\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Num\u00e9ro de mod\u00e8le\u00a0:\n                <\/dt>\n<dd>\n<p>S\u00e9rie T et s\u00e9rie Z<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Puissance nominale :\n                <\/dt>\n<dd>\n<p>0,04-160 kW<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Agencement des engrenages :\n                <\/dt>\n<dd>\n<p>Biseau \/ Onglet<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Couple de sortie\u00a0:\n                <\/dt>\n<dd>\n<p>jusqu'\u00e0 5700 Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>jusqu'\u00e0 1800 tr\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse de sortie :\n                <\/dt>\n<dd>\n<p>3-1450 tr\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Rapport:\n                <\/dt>\n<dd>\n<p>1 \u00e0 5<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Options de structure\u00a0:\n                <\/dt>\n<dd>\n<p>Arbre de sortie simple \/ Arbres de sortie doubles \/ Arbres de sortie triples<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Mode de montage :\n                <\/dt>\n<dd>\n<p>support de pied et support d'arbre<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    couleur:\n                <\/dt>\n<dd>\n<p>bleu RAL 5010 ou gris ou selon les exigences du client<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Standard:\n                <\/dt>\n<dd>\n<p>ISO9001, CE<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Emballer:\n                <\/dt>\n<dd>\n<p>Coffret en bois robuste pour r\u00e9ducteur \u00e0 engrenages coniques h\u00e9lico\u00efdaux s\u00e9rie T<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Huile:\n                <\/dt>\n<dd>\n<p>selon les exigences du client, remplir d'huile ou non<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacit\u00e9 d'approvisionnement<\/p>\n<dl>\n<dt>\n                    Capacit\u00e9 d'approvisionnement :\n                <\/dt>\n<dd>9999999 pi\u00e8ces par mois<\/dd>\n<\/dl>\n<\/p>\n<p><p>Emballage et livraison<\/p>\n<dl>\n<dt>D\u00e9tails de l'emballage<\/dt>\n<dd>Caisses et palettes en bois robustes pour r\u00e9ducteurs agricoles \u00e0 engrenages coniques h\u00e9lico\u00efdaux \u00e0 90\u00b0 s\u00e9rie T<\/dd>\n<\/dl>\n<dl>\n<dt>Port<\/dt>\n<dd>Ningbo ou Shanghai<\/dd>\n<\/dl>\n<dl>\n<dt>\n                        D\u00e9lai de mise en \u0153uvre<br \/>\n                        <i><\/i>:\n                    <\/dt>\n<dd>\n<table>\n<tr>\n<td>Quantit\u00e9 (pi\u00e8ces)<\/td>\n<td>1 &#8211; 200<\/td>\n<td> &gt;200<\/td>\n<\/tr>\n<tr>\n<td>Dur\u00e9e estim\u00e9e (jours)<\/td>\n<td>30<\/td>\n<td>\u00c0 n\u00e9gocier<\/td>\n<\/tr>\n<\/table>\n<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personnalisation en ligne<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Description de la vid\u00e9o<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>Description du produit<\/p>\n<\/p>\n<p>\n<p>1. R\u00e9ducteur \u00e0 engrenages coniques h\u00e9lico\u00efdaux s\u00e9rie T<\/p>\n<p>2. Un r\u00e9ducteur \u00e0 engrenages coniques \u00e0 spirale en T, qu'il s'agisse d'une transmission \u00e0 basse ou haute vitesse, est \u00e9quivalent.<br \/>3. Faible niveau sonore, faibles vibrations et capacit\u00e9 de charge \u00e9lev\u00e9e. Transmission fluide, faible niveau sonore et vibrations, bonne capacit\u00e9 de charge.<br \/>4 Donn\u00e9es techniques : Plage de couple : Jusqu'\u00e0 5000 N\u00b7m <br \/> Puissance absorb\u00e9e\u00a0: de 0,12\u00a0kW \u00e0 96\u00a0kW <br \/> Rapport: <b>1:1\/ 1:1.5\/  1:2 \/ 1:2.5\/ 1:3 <\/b><\/p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p><b>Nom du produit<\/b><\/p>\n<\/td>\n<td>\n<p>R\u00e9ducteur \u00e0 engrenages coniques h\u00e9lico\u00efdaux s\u00e9rie T<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><b>Type d'engrenage<\/b><\/p>\n<\/td>\n<td>\n<p>Engrenages coniques<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><b>Couleur<\/b><\/p>\n<\/td>\n<td>\n<p>Bleu, gris ou personnalis\u00e9<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><b>Standard<\/b><\/p>\n<\/td>\n<td>\n<p>ISO9001:2008\/CE<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><b>Brade<\/b><\/p>\n<\/td>\n<td>\n<p>EVERGEAR<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p><b>Options de structure<\/b><\/p>\n<\/td>\n<td>\n<p>Arbre de sortie simple \/ Arbres de sortie doubles \/ Arbres de sortie triples <\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<p>Pr\u00e9sentation des produits<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Notre service<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Haute qualit\u00e9<\/h3>\n<\/p>\n<p><p>Obtention de la certification du syst\u00e8me de qualit\u00e9 ISO9001:2008<\/p>\n<\/p>\n<p>\n<h3>Service d'application<\/h3>\n<\/p>\n<p><p>Nous vous aiderons \u00e0 trouver une solution d'entra\u00eenement par engrenages abordable, de haute qualit\u00e9 et \u00e9co\u00e9nerg\u00e9tique, parfaitement adapt\u00e9e \u00e0 votre application industrielle.<\/p>\n<\/p>\n<p>\n<h3>Service en ligne<\/h3>\n<\/p>\n<p><p>Service disponible 24h\/24 et 7j\/7 (WhatsApp\/Skype\/E-mail\/Appel t\u00e9l\u00e9phonique)<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Notre entreprise<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><h3>Usine<\/h3>\n<\/p>\n<p>Notre usine<\/p>\n<\/p>\n<p>\n<h3>Atelier<\/h3>\n<\/p>\n<p><p>Notre atelier<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><h3>Entrep\u00f4t<\/h3>\n<\/p>\n<p><p>Notre entrep\u00f4t<\/p>\n<\/p>\n<p>\n<h3>\u00c9quipe<\/h3>\n<\/p>\n<p><p>Notre \u00e9quipe<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Emballage et livraison<\/p>\n<\/p>\n<p>\n<p>D\u00e9tails de l'emballage\u00a0: Emballage \u00e9tanche, caisse en bois robuste, certificat de fumigation<\/p>\n<p>D\u00e9lai de livraison : 3 \u00e0 40 jours par avion ou par bateau (selon la destination)<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p>1. Les motor\u00e9ducteurs sont fix\u00e9s sur le pied \u00e0 l'aide de vis.<\/p>\n<\/p>\n<p><p>2. Monter sur palette<\/p>\n<\/p>\n<p><p>3. Rempli de films<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p>4. Caisses en bois fumantes<\/p>\n<\/p>\n<p><p>5. Caisses et palettes en bois robustes<\/p>\n<\/p>\n<p><p>6. Caisses marqu\u00e9es pour la livraison<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Nos certifications<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<p>\n<p><h3><\/h3>\n<\/p>\n<p><p>ISO9001:2008 \/ CE \/ ISO18001 \/ Une des marques chinoises les plus r\u00e9put\u00e9es de r\u00e9ducteurs.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Photo du client<\/p>\n<\/p>\n<p>\n<p><h3>Fournisseur fiable de transmissions par engrenages<\/h3>\n<\/p>\n<p><p>Produits de haute qualit\u00e9 <br \/>Syst\u00e8me de contr\u00f4le qualit\u00e9 CE, ISO 9001:2008 et ISO 18001<br \/>*Garantie de 12 mois, la meilleure du secteur<br \/>Prix \u200b\u200bd'usine<br \/>Service 24h\/24 et 7j\/7 <\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<h3><\/h3>\n<h3><\/h3>\n<h3><\/h3>\n<h3>Marques des clients<\/h3>\n<\/p>\n<p><p><\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3><\/h3>\n<h3><\/h3>\n<h3>Marques des clients<\/h3>\n<\/p>\n<p><p><\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>FAQ<\/p>\n<\/p>\n<p>\n<p><h3>Q : \u00cates-vous une soci\u00e9t\u00e9 commerciale ou un fabricant ?<\/h3>\n<\/p>\n<p><p>A: Nous sommes une usine. Notre usine est situ\u00e9e dans le comt\u00e9 de Pingyang, ville de Wenzhou, province du Zhejiang, en Chine.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Q : Quel est votre d\u00e9lai de livraison ?<\/h3>\n<\/p>\n<p><p>A : G\u00e9n\u00e9ralement, le d\u00e9lai est de 20 \u00e0 30 jours si les marchandises sont en stock, et de 15 \u00e0 20 jours si elles ne le sont pas, selon la quantit\u00e9.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Q : Fournissez-vous des \u00e9chantillons ? Sont-ils gratuits ou payants ?<\/h3>\n<\/p>\n<p><p>A: Oui, nous pouvons vous proposer un \u00e9chantillon, frais d'\u00e9chantillon et de transport inclus.<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Q : Quelles sont vos conditions de paiement ?<\/h3>\n<\/p>\n<p><p>A: 30% T\/T \u00e0 l'avance, solde avant exp\u00e9dition.<\/p>\n<p>Si vous avez d'autres questions, n'h\u00e9sitez pas \u00e0 nous contacter comme indiqu\u00e9 ci-dessous\u00a0:<br \/>N'h\u00e9sitez pas \u00e0 me contacter pour toute question ou besoin suppl\u00e9mentaire, 24h\/24 et 7j\/7 !<br \/>Personne \u00e0 contacter : Mme Zember Liu (Skype : zemberliu) Mobil : +86 139 6777 5116 (What'sAPP)<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Model Number: T series and Zseries Rated Power: 0.04-160KW Gearing Arrangement: Bevel \/ Miter Output Torque: up to 5700Nm Input Speed: up to 1800rpm Output Speed: 3-1450rpm Ratio: 1 to 5 Structure Options: Single output shaft \/ Double output shafts \/three output shafts Mounting [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-286","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"predecessor-version":[{"id":2071,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/286\/revisions\/2071"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}