{"id":284,"date":"2020-01-14T08:14:22","date_gmt":"2020-01-14T08:14:22","guid":{"rendered":"http:\/\/gearboxagricultural.com\/agricultural-gearbox-for-harvest-fruits\/"},"modified":"2020-07-08T03:45:44","modified_gmt":"2020-07-08T03:45:44","slug":"agricultural-gearbox-for-harvest-fruits","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/fr_fr\/application\/agricultural-gearbox-for-harvest-fruits\/","title":{"rendered":"Bo\u00eete de vitesses agricole pour la r\u00e9colte des fruits"},"content":{"rendered":"<p>\n<p>\n<p>Aper\u00e7u<\/p>\n<p>\n<p><p>D\u00e9tails rapides<\/p>\n<dl>\n<dt>\n                    Lieu d'origine :\n                <\/dt>\n<dd>\n<p>Zhejiang, Chine<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom de marque :\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Agencement des engrenages :\n                <\/dt>\n<dd>\n<p>Ver<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Couple de sortie\u00a0:\n                <\/dt>\n<dd>\n<p>&#8211;<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse d'entr\u00e9e :\n                <\/dt>\n<dd>\n<p>&#8211;<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Vitesse de sortie :\n                <\/dt>\n<dd>\n<p>&#8211;<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nom du produit :\n                <\/dt>\n<dd>\n<p>Bo\u00eete de vitesses agricole pour la r\u00e9colte des fruits<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacit\u00e9 d'approvisionnement<\/p>\n<dl>\n<dt>\n                    Capacit\u00e9 d'approvisionnement :\n                <\/dt>\n<dd>100 000 pi\u00e8ces par semaine<\/dd>\n<\/dl>\n<\/p>\n<p><p>Emballage et livraison<\/p>\n<dl>\n<dt>D\u00e9tails de l'emballage<\/dt>\n<dd>Coffret en bois<\/dd>\n<\/dl>\n<dl>\n<dt>Port<\/dt>\n<dd>Shanghai\/Ningbo<\/dd>\n<\/dl>\n<dl>\n<dt>\n                        D\u00e9lai de mise en \u0153uvre<br \/>\n                        <i><\/i>:\n                    <\/dt>\n<dd>\n<table>\n<tr>\n<td>Quantit\u00e9 (pi\u00e8ces)<\/td>\n<td>1 &#8211; 1<\/td>\n<td> &gt;1<\/td>\n<\/tr>\n<tr>\n<td>Dur\u00e9e estim\u00e9e (jours)<\/td>\n<td>30<\/td>\n<td>\u00c0 n\u00e9gocier<\/td>\n<\/tr>\n<\/table>\n<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personnalisation en ligne<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>Description du produit<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p><h3>Bo\u00eete de vitesses agricole pour la r\u00e9colte des fruits<\/h3>\n<p><\/p>\n<\/p>\n<p><p>Machine harvesting is going to shape the future of the World apple and pear and other fruits industries, and could reduce manual harvesting costs by half . So the demand of this type of gearbox increase day by day.<\/p>\n<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>Nom du produit<\/p>\n<\/td>\n<td>\n<p>Bo\u00eete de vitesses agricole pour la r\u00e9colte des fruits<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<p>Notre entreprise<\/p>\n<\/p>\n<p>\n<p>Our Group specialist in making all kinds of mechanical transmission and hydraulic transmission like: planetary gearboxes, worm reducers, in-line helical gear speed reducers, parallel shaft helical gear reducers, helical bevel reducers, helical worm gear reducers, agricultural gearboxes, tractor gearboxes, auto gearboxes, pto drive shafts, special reducer &amp; related gear components and other related products, sprockets, hydraulic system, vaccum pumps, fluid coupling, gear racks, chains, timing pulleys, udl speed variators, v pulleys, hydraulic cylinder, gear pumps, screw air compressors, shaft collars low backlash worm reducers and so on. furthermore, we can produce customized variators, geared motors, electric motors and other hydraulic products according to customers&#8217; drawings.<\/p>\n<p>We provides a reliable gurantee for the product&#8217; s quality by advanced inspection and testing equipment. professional technical team, exquisite processing technology and strict control system. <\/p>\n<p>Ces derni\u00e8res ann\u00e9es, l'entreprise a connu un d\u00e9veloppement rapide gr\u00e2ce \u00e0 sa riche exp\u00e9rience en production, son syst\u00e8me de gestion avanc\u00e9 et standardis\u00e9, ainsi que sa solide expertise technique. Nous privil\u00e9gions la qualit\u00e9 pour assurer notre p\u00e9rennit\u00e9 et l'innovation scientifique et technologique pour notre d\u00e9veloppement. <\/p>\n<p>Notre groupe est pr\u00eat \u00e0 travailler main dans la main avec vous et \u00e0 cr\u00e9er ensemble des r\u00e9sultats exceptionnels !<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><p>Atelier de meulage<\/p>\n<\/p>\n<p>\n<p>Machine \u00e0 dents CNC<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><p>Atelier de tournage CNC<\/p>\n<\/p>\n<p>\n<p>Centre de figuration<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><p>Atelier CNC<\/p>\n<\/p>\n<p>\n<p>Machine de traitement thermique<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><p>Machines de mesure 3D<\/p>\n<\/p>\n<p>\n<p>Machines d'essai de profil de dent d'engrenage<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<\/p>\n<p>\n<p><p>Atelier de traitement thermique<\/p>\n<\/p>\n<p>\n<p>Atelier sur le profil dentaire<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p><h3>Mat\u00e9riel disponible<br \/><\/h3>\n<\/p>\n<p><p>Acier \u00e0 faible teneur en carbone, C45, 20CrMnTi, 42CrMo, 40Cr, acier inoxydable. Adaptable aux exigences du client.<\/p>\n<\/p>\n<p>\n<h3>Traitement de surface<br \/><\/h3>\n<\/p>\n<p><p>Noircissement, galvanisation, chromage, \u00e9lectrophor\u00e8se, peinture en couleur, \u2026<\/p>\n<\/p>\n<p>\n<h3>Traitement thermique<br \/><\/h3>\n<\/p>\n<p><p>Traitement thermique par trempe \u00e0 haute fr\u00e9quence, dents tremp\u00e9es, carbonisation, nitruration, \u2026<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Certifications<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>FAQ<\/p>\n<\/p>\n<p>\n<p>Q : \u00cates-vous une soci\u00e9t\u00e9 commerciale ou un fabricant ?<br \/>A: Notre groupe se compose de 3 usines et de 2 filiales commerciales \u00e0 l'\u00e9tranger.<br \/>Q : Fournissez-vous des \u00e9chantillons ? Sont-ils gratuits ou payants ?<br \/>R : Oui, nous pouvons vous offrir l'\u00e9chantillon gratuitement, mais les frais de transport sont \u00e0 votre charge.<\/p>\n<p>Q : Quel est votre d\u00e9lai de livraison ? Quelles sont vos conditions de paiement ?<br \/>R : G\u00e9n\u00e9ralement, le d\u00e9lai est de 40 \u00e0 45 jours. Ce d\u00e9lai peut varier en fonction du produit et du niveau de personnalisation. Pour les produits standard, le paiement s'effectue par virement bancaire (30%) \u00e0 l'avance, le solde \u00e9tant d\u00fb avant l'exp\u00e9dition.<\/p>\n<p>Q : Quel est le MOQ exact ou le prix de votre produit ?<br \/>A: En tant que fabricant d'\u00e9quipement d'origine (OEM), nous pouvons adapter nos produits \u00e0 une large gamme de besoins. Par cons\u00e9quent, la quantit\u00e9 minimale de commande (MOQ) et le prix peuvent varier consid\u00e9rablement en fonction de la taille, du mat\u00e9riau et des sp\u00e9cifications. Par exemple, les produits haut de gamme ou standard ont g\u00e9n\u00e9ralement une MOQ plus faible. Veuillez nous contacter en nous fournissant tous les d\u00e9tails pertinents afin d'obtenir un devis pr\u00e9cis.<\/p>\n<p>Si vous avez d'autres questions, n'h\u00e9sitez pas \u00e0 nous contacter.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Emballage et livraison<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Notre service<\/p>\n<\/p>\n<p>\n<p>J'aimerais \u00e9galement profiter de cette occasion pour vous pr\u00e9senter bri\u00e8vement notre soci\u00e9t\u00e9 Ever-Power\u00a0:<\/p>\n<p>Notre entreprise est un fabricant renomm\u00e9 de bo\u00eetes de vitesses agricoles, de r\u00e9ducteurs \u00e0 vis sans fin, d'arbres de prise de force, de pignons, de cha\u00eenes \u00e0 rouleaux, d'engrenages coniques, de poulies et de cr\u00e9maill\u00e8res en Chine.<\/p>\n<p>Nous avons export\u00e9 de nombreux produits \u00e0 nos clients du monde entier, nous b\u00e9n\u00e9ficions d'une longue exp\u00e9rience et d'un solide soutien technologique. <\/p>\n<p>Quelques-uns de nos clients :<br \/>Italy: COMER,GB GEABOX ,SATI, CHIARAVALLI, AMA , Brevini<br \/>Allemagne : SILOKING, GKN, KTS<br \/>France : Itfran, Sedies<br \/>Br\u00e9sil : AEMCO, STU <br \/>\u00c9tats-Unis : John Deere, Blount, Weasler, Agco, Omni Gear, Woods<br \/>Canada : JAY-LOR, CANIMEX, RingBall<br \/>&#8230;&#8230;<\/p>\n<p>-&Oslash; Our Company with over twelve year&#8217;s history and 1000 workers and 20 sales.<br \/>-&Oslash; With over 100 Million USD sales in 2017<br \/>-&Oslash; With advance machinery equipments<br \/>-&Oslash; With large work capacity and high quality control, ISO certified.<br \/>&#8230;&#8230;<\/p>\n<p>Vous pouvez \u00e9galement consulter notre site web pour plus de d\u00e9tails ; si vous souhaitez recevoir notre catalogue de produits, veuillez nous contacter.<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Worm Output Torque: &#8211; Input Speed: &#8211; Output Speed: &#8211; Product name: Agricultural Gearbox For Harvest Fruits Supply Ability Supply Ability: 100000 Piece\/Pieces per Week Packaging &amp; Delivery Packaging Details Wooden Case Port Shanghai\/ Ningbo Lead Time : Quantity(Pieces) 1 &#8211; 1 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-284","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/284\/revisions"}],"predecessor-version":[{"id":2074,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/posts\/284\/revisions\/2074"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}