{"id":356,"date":"2020-01-14T08:15:25","date_gmt":"2020-01-14T08:15:25","guid":{"rendered":"http:\/\/gearboxagricultural.com\/gearbox-for-agricultural-machinery-worm-gear-reducer-gearbox-prices-gear-motor\/"},"modified":"2020-07-08T03:45:39","modified_gmt":"2020-07-08T03:45:39","slug":"caja-de-cambios-para-maquinaria-agricola-reductor-de-tornillo-sin-fin-precios-de-cajas-de-cambios-motorreductor","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/es\/application\/caja-de-cambios-para-maquinaria-agricola-reductor-de-tornillo-sin-fin-precios-de-cajas-de-cambios-motorreductor\/","title":{"rendered":"Caja de cambios para maquinaria agr\u00edcola, reductor de tornillo sin fin, precios de cajas de cambios, motorreductor"},"content":{"rendered":"<p>\n<p>\n<p>Descripci\u00f3n general<\/p>\n<p>\n<p><p>Detalles r\u00e1pidos<\/p>\n<dl>\n<dt>\n                    Lugar de origen:\n                <\/dt>\n<dd>\n<p>Zhejiang, China<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nombre de la marca:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    N\u00famero de modelo:\n                <\/dt>\n<dd>\n<p>Caja de cambios de transmisi\u00f3n de potencia RV\/NRV\/NMRV25~150 nmrv<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Potencia nominal:\n                <\/dt>\n<dd>\n<p>0,06 kW ~ 7,5 kW<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Disposici\u00f3n de engranajes:\n                <\/dt>\n<dd>\n<p>Gusano<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Par de salida:\n                <\/dt>\n<dd>\n<p>2,6 Nm ~ 2379 Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidad de entrada:\n                <\/dt>\n<dd>\n<p>750~3000 rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidad de salida:\n                <\/dt>\n<dd>\n<p>10-400 rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Certificado:\n                <\/dt>\n<dd>\n<p>ISO9001, CE, CCC<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Posici\u00f3n de montaje:\n                <\/dt>\n<dd>\n<p>Horizontal (montado en el pie) o vertical (montado en la brida)<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Color:\n                <\/dt>\n<dd>\n<p>Seg\u00fan solicitud del cliente<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Material:\n                <\/dt>\n<dd>\n<p>Acero o hierro fundido<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Material del engranaje:\n                <\/dt>\n<dd>\n<p>20CrMnTiH<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Relaci\u00f3n de transmisi\u00f3n:\n                <\/dt>\n<dd>\n<p>7.5 -100<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Precisi\u00f3n del engranaje:\n                <\/dt>\n<dd>\n<p>GBT3~6<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Eje sin fin:\n                <\/dt>\n<dd>\n<p>40Cr<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Servicio:\n                <\/dt>\n<dd>\n<p>24 horas<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nombre:\n                <\/dt>\n<dd>\n<p>Caja reductora NMRV para maquinaria agr\u00edcola<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacidad de suministro<\/p>\n<dl>\n<dt>\n                    Capacidad de suministro:\n                <\/dt>\n<dd>Caja de cambios de 500 juegos por semana para maquinaria agr\u00edcola<\/dd>\n<\/dl>\n<\/p>\n<p><p>Embalaje y entrega<\/p>\n<dl>\n<dt>Detalles del embalaje<\/dt>\n<dd>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<br \/>\n<br \/>3. Seg\u00fan los requisitos del cliente.<br \/>\n<br \/>Precios de reductores de engranajes helicoidales peque\u00f1os NMRV, reductores de engranajes de transmisi\u00f3n, motorreductores para maquinaria agr\u00edcola\u201d&gt;1, Embalaje industrial: Tubo de pl\u00e1stico + cart\u00f3n + pal\u00e9s de madera<br \/>\n<br \/>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<br \/>\n<br \/>3. Seg\u00fan los requisitos del cliente.<br \/>\n<br \/>Precios de cajas de engranajes helicoidales peque\u00f1os NMRV, reductores de transmisi\u00f3n, motorreductores para maquinaria agr\u00edcola<\/dd>\n<\/dl>\n<dl>\n<dt>Puerto<\/dt>\n<dd>Llevar a la fuerza<\/dd>\n<\/dl>\n<dl>\n<dt>\n                        plazo de entrega<br \/>\n                        <i><\/i>:\n                    <\/dt>\n<dd>\n                        Caja de cambios para maquinaria agr\u00edcola con entrega en 3-5 d\u00edas.\n                      <\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personalizaci\u00f3n en l\u00ednea<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p><strong>Caja de cambios NMRV para maquinaria agr\u00edcola, reductor de engranajes helicoidales, precios de cajas de cambios, motorreductor, caja de cambios de transmisi\u00f3n de potencia <\/strong><\/p>\n<p><strong>reductor de engranajes helicoidales <\/strong><\/p>\n<p><strong>reductor de engranajes helicoidales para veh\u00edculos recreativos <\/strong><\/p>\n<p><strong>reductor de engranajes helicoidales peque\u00f1os <\/strong><\/p>\n<\/p>\n<\/p>\n<p><p>Descripci\u00f3n del Producto<\/p>\n<\/p>\n<p><strong> Caja de cambios para maquinaria agr\u00edcola  <\/strong><\/p>\n<p><strong>Descripci\u00f3n general del producto:<\/strong><\/p>\n<p>1. Dise\u00f1o y fabricaci\u00f3n de engranajes helicoidales RV seg\u00fan est\u00e1ndares de calidad t\u00e9cnica Q\/MD1-2000.<\/p>\n<p>2. El producto cumple con los par\u00e1metros del est\u00e1ndar nacional GB10085-88 basados \u200b\u200ben la rueda helicoidal, el reductor helicoidal aprende la tecnolog\u00eda m\u00e1s avanzada, el estilo novedoso y \u00fanico de \"caja cuadrada\" en la estructura exterior, la apariencia del gabinete y la fundici\u00f3n a presi\u00f3n de aluminio de calidad.<\/p>\n<p>3, el reductor de engranajes helicoidales RV se ha utilizado ampliamente en maquinaria y equipos en metalurgia, miner\u00eda, transporte, agua, productos qu\u00edmicos, alimentos, bebidas, textiles, tabaco, embalaje, protecci\u00f3n del medio ambiente y muchas otras industrias y campos de tecnolog\u00eda y equipos, elogiado por los usuarios, es un gran equipo industrial moderno para lograr una relaci\u00f3n de bajo ruido, la mejor opci\u00f3n para el control de transmisi\u00f3n de desaceleraci\u00f3n de dispositivos mec\u00e1nicos de alta estabilidad.<\/p>\n<\/p>\n<p><strong>Caracter\u00edsticas:<\/strong><\/p>\n<p>1, la estructura mec\u00e1nica es compacta, liviana, compacta y eficiente, buen rendimiento de intercambio de calor, r\u00e1pida disipaci\u00f3n de calor;<\/p>\n<p>2, f\u00e1cil de instalar, flexible y \u00e1gil, rendimiento superior, facilidad de mantenimiento y revisi\u00f3n;<\/p>\n<p>3, gran relaci\u00f3n de transmisi\u00f3n, par, capacidad de soportar alta sobrecarga;<\/p>\n<p>4, funcionamiento suave, bajo nivel de ruido, duradero; aplicabilidad, seguridad y confiabilidad de gran tama\u00f1o.<\/p>\n<\/p>\n<p><strong>Par\u00e1metros t\u00e9cnicos:<\/strong><\/p>\n<p>Potencia: 0,06 KW ~ 7,5 KW<\/p>\n<p>Par motor: 2,6 Nm ~ 2379 Nm<\/p>\n<p>Relaci\u00f3n de transmisi\u00f3n: 7,5-100<\/p>\n<p> caja de cambios de transmisi\u00f3n de potencia <\/p>\n<p><strong>El modelo b\u00e1sico:<\/strong><\/p>\n<p>RV25RV30RV40RV50RV63RV75RV90RV110RV130RV150<\/p>\n<p>NRV25NRV30NRV40NRV50NRV63NRV75NRV90NRV110NRV130NRV150<\/p>\n<p>NMRV25NMRV30NMRV40NMRV50NMRV63NMRV75NMRV90NMRV110NMRV130NMRV150<\/p>\n<\/p>\n<p><p>Embalaje y env\u00edo<\/p>\n<\/p>\n<\/p>\n<p><strong>Reductor de engranajes helicoidales NMRV, caja de cambios de avance y retroceso para maquinaria agr\u00edcola <\/strong><\/p>\n<p><strong>1. Embalaje industrial: tubo de pl\u00e1stico, cart\u00f3n y pal\u00e9s de madera.<\/strong><br \/><strong>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<\/strong><br \/><strong>3. Seg\u00fan los requisitos del cliente. <\/strong><\/p>\n<p><strong>4. Env\u00edo: por mar, por aire, por DHL, Fedex, UPS, etc.<\/strong><\/p>\n<\/p>\n<\/p>\n<p><p>Informaci\u00f3n de la empresa<\/p>\n<\/p>\n<p>Como fabricante l\u00edder de motores industriales, reductores de velocidad, accionamientos, etc. en China, nuestra empresa siempre se ha adherido al concepto de \"innovaci\u00f3n tecnol\u00f3gica l\u00edder, logrando una calidad excelente\", los productos principales son: micromotores de engranajes, motores de engranajes de tama\u00f1o mediano, motores de regulaci\u00f3n de velocidad de freno, motores de par, motores de CC, motor de tornillo sin fin NMRV, motores de engranajes c\u00f3nicos helicoidales, reductor de tornillo sin fin de la serie WP RV, unidades de engranajes helicoidales de flanco de diente r\u00edgido, unidades de engranajes helicoidales de tornillo sin fin, unidades de engranajes helicoidales de eje paralelo, unidades de engranajes c\u00f3nicos en espiral, gato de tornillo sin fin SWL y JW, unidades de engranajes de flanco de diente r\u00edgido, unidades de engranajes planetarios, etc. productos de transmisi\u00f3n, que se utilizan ampliamente en varias l\u00edneas de producci\u00f3n industrial, como maquinaria de transporte, maquinaria alimentaria, maquinaria m\u00e9dica, maquinaria de impresi\u00f3n, maquinaria textil, maquinaria de embalaje, equipo de oficina, instrumentaci\u00f3n y otros campos, son los productos de soporte preferidos para equipos de automatizaci\u00f3n.<\/p>\n<\/p>\n<p><strong>\u00bfPOR QU\u00c9 ELEGIRNOS?<\/strong><br \/> -EXCELENTE SERVICIO, BAJOS COSTOS, ALTA ESTABILIDAD, CALIDAD AVANZADA, FUERZA LABORAL ESTABLE<br \/> -Poseemos alrededor de 300 juegos de equipos de procesamiento y equipos de prueba para garantizar la alta precisi\u00f3n y calidad, como la rectificadora de engranajes de precisi\u00f3n REISHAUER (Suiza), la fresadora de engranajes PFAUTER (Alemania), la fresadora de engranajes c\u00f3nicos Gleason, la m\u00e1quina de medici\u00f3n de tres coordenadas, etc.<\/p>\n<\/p>\n<p><p>Nuestros servicios<\/p>\n<\/p>\n<ul>\n<li>Entrega a tiempo<\/li>\n<li>Servicio 24 horas<\/li>\n<li>Calidad garantizada<\/li>\n<li>Visita a la f\u00e1brica de apoyo<\/li>\n<li>Soportes tecnol\u00f3gicos<\/li>\n<\/ul>\n<p><strong> Reductor de engranajes helicoidales NMRV para maquinaria agr\u00edcola <\/strong><\/p>\n<\/p>\n<ul>\n<li>El equipo de Shanghai Taiqi agradece sinceramente su consulta y cooperaci\u00f3n.<\/li>\n<li>\u00a1Agradecemos mucho su visita!<\/li>\n<\/ul>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Model Number: RV\/NRV\/NMRV25~150 nmrv power transmission gearbox Rated Power: 0.06KW ~ 7.5KW Gearing Arrangement: Worm Output Torque: 2.6N.m ~ 2379N.m Input Speed: 750~3,000 Rpm Output Speed: 10-400 Rpm Certificate: ISO9001, CE, CCC Mounting Position: Horizontal (foot mounted) or Vertical (flange mounted) Color: According to [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-356","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"predecessor-version":[{"id":2001,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/356\/revisions\/2001"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}