{"id":336,"date":"2020-01-14T08:15:07","date_gmt":"2020-01-14T08:15:07","guid":{"rendered":"http:\/\/gearboxagricultural.com\/agricultural-gearbox-for-lawn-mowers\/"},"modified":"2020-07-08T03:45:40","modified_gmt":"2020-07-08T03:45:40","slug":"agricultural-gearbox-for-lawn-mowers","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/es\/application\/agricultural-gearbox-for-lawn-mowers\/","title":{"rendered":"Caja de cambios agr\u00edcola para cortac\u00e9spedes"},"content":{"rendered":"<p>\n<p>\n<p>Descripci\u00f3n general<\/p>\n<p>\n<p><p>Detalles r\u00e1pidos<\/p>\n<dl>\n<dt>\n                    Lugar de origen:\n                <\/dt>\n<dd>\n<p>Zhejiang, China<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nombre de la marca:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Industrias aplicables:\n                <\/dt>\n<dd>\n<p>Plantas de fabricaci\u00f3n, talleres de reparaci\u00f3n de maquinaria, granjas<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacidad de suministro<\/p>\n<dl>\n<dt>\n                    Capacidad de suministro:\n                <\/dt>\n<dd>100000 piezas por mes<\/dd>\n<\/dl>\n<\/p>\n<p><p>Embalaje y entrega<\/p>\n<dl>\n<dt>Detalles del embalaje<\/dt>\n<dd>Carton\/Wooden<\/dd>\n<\/dl>\n<dl>\n<dt>Puerto<\/dt>\n<dd>Ningbo\/Shangh\u00e1i<\/dd>\n<\/dl>\n<dl>\n<dt>\n                        plazo de entrega<br \/>\n                        <i><\/i>:\n                    <\/dt>\n<dd>\n                        Env\u00edo en 0 d\u00edas despu\u00e9s del pago.\n                      <\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personalizaci\u00f3n en l\u00ednea<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p>\n<p>\n<p>Descripci\u00f3n del Producto<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Agricultural Gearbox For Maintenance of Green Spaces<br \/>Power transmission systems designed to the specific needs of machinery for gardening and maintenance of green spaces.<br \/>Caja de cambios agr\u00edcola para cortac\u00e9spedes<br \/>Lawn Mowers Gearbox, Lawn Mowers Agricultural Gearbox<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>1. Stainless Steel: SS201, SS303, SS304, SS316, SS416, SS420<br \/>2. Steel:C45(K1045), C46(K1046),C20<br \/>3. Brass:C36000 ( C26800), C37700 ( HPb59), C38500( HPb58), C27200(CuZn37), C28000(CuZn40)<br \/>4. Bronze: C51000, C52100, C54400, etc<br \/>5. Iron: 1213, 12L14,1215<br \/>6. Aluminum: Al6061, Al6063<br \/>7.OEM according to your request<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Productos relacionados<\/p>\n<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>Caja de cambios para cultivador rotativo<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para esparcidores de fertilizantes<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para henificadora<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para cortadora rotativa<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para segadoras rotativas<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes de toma de fuerza agr\u00edcolas para generadores el\u00e9ctricos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes para excavadora de postes<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para remolque autocargable<\/p>\n<\/td>\n<td>\n<p>Caja de cambios general para maquinaria agr\u00edcola<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes agr\u00edcola para esparcidor de esti\u00e9rcol<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes para sistemas distribuidores de silos<\/p>\n<\/td>\n<td>\n<p>Motor de transmisi\u00f3n del sistema de riego<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes agr\u00edcola para esparcidor de fertilizantes<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes para picadoras de heno<\/p>\n<\/td>\n<td>\n<p>Caja de cambios de transmisi\u00f3n del sistema de riego<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para pulverizadores<\/p>\n<\/td>\n<td>\n<p>Cajas de cambios para empacadoras<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes de inmersi\u00f3n central del sistema de riego<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para segadora de mayales<\/p>\n<\/td>\n<td>\n<p>Multiplicador de cajas de cambios para sistemas de bombas hidr\u00e1ulicas<\/p>\n<\/td>\n<td>\n<p>Aumentador de velocidad de la caja de cambios con accionamiento hidr\u00e1ulico de la toma de fuerza<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para cortac\u00e9spedes<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes planetarios para excavadora de accionamiento hidr\u00e1ulico en l\u00ednea<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes de rastrillo de entrega lateral<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para generador<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para la cosecha de frutas<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes planetarios para mezcladoras de pienso<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para microcultivador<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para limpieza de ganado<\/p>\n<\/td>\n<td>\n<p>Reductor de velocidad de la toma de fuerza<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios agr\u00edcola para hormigonera<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para transmisi\u00f3n de excavadora<\/p>\n<\/td>\n<td>\n<p>Cajas de cambios Slasher<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes agr\u00edcola para mezcladora de pienso<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para el sistema de accionamiento de la secadora<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes de barrena<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Agitadores para aguas residuales<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para bombas de laguna<\/p>\n<\/td>\n<td>\n<p>Caja de cambios reversible de la cosechadora de granos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Cajas de engranajes para esparcidores de sal<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes c\u00f3nicos para planta generadora de energ\u00eda de biog\u00e1s<\/p>\n<\/td>\n<td>\n<p>Caja de cambios de la bomba de aceite<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Reductor de caja de cambios para sistema de accionamiento de pantallas clim\u00e1ticas<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para sierras circulares y sierras de cinta<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes de la cosechadora de patatas<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios y reductor para sistemas de transmisi\u00f3n de almacenamiento de cultivos<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para motocultores<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes del pulverizador de pesticidas<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Reductor de caja de cambios para sistemas de transmisi\u00f3n de horticultura<\/p>\n<\/td>\n<td>\n<p>Caja de cambios para hormigoneras<\/p>\n<\/td>\n<td>\n<p>Pi\u00f1ones de cadena Caja de cambios<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Sistemas de accionamiento para ventilaci\u00f3n en ganader\u00eda<\/p>\n<\/td>\n<td>\n<p>Transmisi\u00f3n de giro con engranaje helicoidal para cuchara de madera<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes para transportador de granos agr\u00edcola<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Enrollador de pel\u00edcula el\u00e9ctrico con cabrestante para ventilaci\u00f3n de invernaderos con pel\u00edcula de polietileno<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes agr\u00edcola para gradas rotativas<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes de la cosechadora Caja de engranajes c\u00f3nicos reversibles<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes para gradas rotativas<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para vi\u00f1edos<\/p>\n<\/td>\n<td>\n<p>Caja de cambios reversible<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de engranajes para cultivadores rotativos<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para desbrozadoras<\/p>\n<\/td>\n<td>\n<p>Cajas de engranajes para cortadoras rotativas tama\u00f1o EP70<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios para zanjadoras<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para segadoras offset<\/p>\n<\/td>\n<td>\n<p>Motorreductores para sistemas de alimentaci\u00f3n de aves y cerdos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios entre bombas para accionamiento de PTO<\/p>\n<\/td>\n<td>\n<p>Caja de cambios agr\u00edcola para segadoras de mayales<\/p>\n<\/td>\n<td>\n<p>Caja de engranajes de cadena de pi\u00f1\u00f3n del esparcidor de sal<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Caja de cambios para Dusters<\/p>\n<\/td>\n<td>\n<\/td>\n<td>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>\n<p>Nuestra empresa<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Certificaciones<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Embalaje y entrega<\/p>\n<\/p>\n<p>\n<\/p>\n<p>\n<p>Tambi\u00e9n me gustar\u00eda aprovechar esta oportunidad para dar una breve introducci\u00f3n de nuestra empresa Ever-Power:<\/p>\n<p>Nuestra empresa es un famoso fabricante de cajas de engranajes agr\u00edcolas, cajas de engranajes reductores de tornillo sin fin, ejes PTO, pi\u00f1ones, cadenas de rodillos, engranajes c\u00f3nicos, poleas y cremalleras en China.<\/p>\n<p>Hemos exportado muchos productos a nuestros clientes de todo el mundo, tenemos una larga experiencia y un s\u00f3lido respaldo tecnol\u00f3gico. <\/p>\n<p>Algunos de nuestros clientes:<br \/>Italia: COMER, GB GEABOX, SATI, CHIARAVALLI, AMA, Brevini<br \/>Alemania: SILOKING, GKN, KTS<br \/>Francia: Itfran, Sedies<br \/>Brasil: AEMCO, STU <br \/>EE. UU.: John Deere, BLOUNT, Weasler, Agco, Omni Gear, WOODS<br \/>Canad\u00e1: JAY-LOR, CANIMEX, RingBall<br \/>&#8230;&#8230;<br \/>-\u00d8 Nuestra Empresa con m\u00e1s de doce a\u00f1os de historia y 1000 trabajadores y 20 ventas.<br \/>-\u00d8 Con m\u00e1s de 100 millones de d\u00f3lares en ventas en 2017<br \/>-\u00d8 Con equipos de maquinaria avanzados<br \/>-\u00d8 Con gran capacidad de trabajo y alto control de calidad, certificado ISO.<br \/>&#8230;&#8230;<br \/>Tambi\u00e9n puede consultar nuestro sitio web para obtener m\u00e1s detalles. Si necesita nuestro cat\u00e1logo de productos, cont\u00e1ctenos.<\/p>\n<\/p>\n<\/p>\n<p>\n<p>Cont\u00e1ctenos<\/p>\n<\/p>\n<p>\n<\/p>\n<\/p>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Applicable Industries: Manufacturing Plant, Machinery Repair Shops, Farms Supply Ability Supply Ability: 100000 Piece\/Pieces per Month Packaging &amp; Delivery Packaging Details Carton\/Wooden Port Ningbo\/Shanghai Lead Time : Shipped in 0 days after payment Online Customization Product Description Agricultural Gearbox For Maintenance of Green SpacesPower [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-336","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/336\/revisions"}],"predecessor-version":[{"id":2021,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/336\/revisions\/2021"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/categories?post=336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}