{"id":300,"date":"2020-01-14T08:14:37","date_gmt":"2020-01-14T08:14:37","guid":{"rendered":"http:\/\/gearboxagricultural.com\/gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox\/"},"modified":"2020-07-08T03:45:43","modified_gmt":"2020-07-08T03:45:43","slug":"gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox","status":"publish","type":"post","link":"https:\/\/gearboxagricultural.com\/es\/application\/gearbox-for-agricultural-machinery-extruder-zlyj-extruder-gearbox\/","title":{"rendered":"gearbox for agricultural machinery extruder ZLYJ extruder gearbox"},"content":{"rendered":"<p>\n<p>\n<p>Descripci\u00f3n general<\/p>\n<p>\n<p><p>Detalles r\u00e1pidos<\/p>\n<dl>\n<dt>\n                    Lugar de origen:\n                <\/dt>\n<dd>\n<p>Zhejiang, China<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nombre de la marca:\n                <\/dt>\n<dd>\n<p>EPT<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Disposici\u00f3n de engranajes:\n                <\/dt>\n<dd>\n<p>Helicoidal<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Par de salida:\n                <\/dt>\n<dd>\n<p>350~100000Nm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidad de entrada:\n                <\/dt>\n<dd>\n<p>1500,1000,750rpm<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Velocidad de salida:\n                <\/dt>\n<dd>\n<p>30-188r\/min<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Certificado:\n                <\/dt>\n<dd>\n<p>ISO9001, CE, CCC<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Mounting position:\n                <\/dt>\n<dd>\n<p>Horizontal (montado en el pie) o vertical (montado en la brida)<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Color:\n                <\/dt>\n<dd>\n<p>Seg\u00fan solicitud del cliente<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Material:\n                <\/dt>\n<dd>\n<p>Acero o hierro fundido<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Material del engranaje:\n                <\/dt>\n<dd>\n<p>Low carbon high alloy steel<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Gear accuracy:\n                <\/dt>\n<dd>\n<p>less than 6<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Calidad:\n                <\/dt>\n<dd>\n<p>Super<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Output Design:\n                <\/dt>\n<dd>\n<p>Solid shaft, hollow shaft, flange<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Tratamiento t\u00e9rmico:\n                <\/dt>\n<dd>\n<p>Carburising\/quenching\/gear grinding<\/p>\n<\/dd>\n<\/dl>\n<dl>\n<dt>\n                    Nombre:\n                <\/dt>\n<dd>\n<p>plastic extruder reducer ZLYJ gearbox for concrete mixer extruder<\/p>\n<\/dd>\n<\/dl>\n<\/p>\n<p><p>Capacidad de suministro<\/p>\n<dl>\n<dt>\n                    Capacidad de suministro:\n                <\/dt>\n<dd>500 Set\/Sets per   Week gearbox for extruder<\/dd>\n<\/dl>\n<\/p>\n<p><p>Embalaje y entrega<\/p>\n<dl>\n<dt>Detalles del embalaje<\/dt>\n<dd>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<br \/>\n<br \/>3. Seg\u00fan los requisitos del cliente.<br \/>\n<br \/>plastic extruder reducer ZLYJ gearbox for extruder&#8221;&gt;1, Industrial pakaging: Plastic tube+carton+wooden pallets<br \/>\n<br \/>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<br \/>\n<br \/>3. Seg\u00fan los requisitos del cliente.<br \/>\n<br \/>plastic extruder reducer ZLYJ gearbox for extruder<\/dd>\n<\/dl>\n<dl>\n<dt>Puerto<\/dt>\n<dd>Llevar a la fuerza<\/dd>\n<\/dl>\n<\/p>\n<p><h3>Personalizaci\u00f3n en l\u00ednea<\/h3>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p>\n<p><strong> plastic extruder reducer ZLYJgearbox for concrete mixer extruder <\/strong><\/p>\n<\/p>\n<p><p>Descripci\u00f3n del Producto<\/p>\n<\/p>\n<p>plastic extruder reducer ZLYJ gearbox for concrete mixer extruder extrudinggearboxes<\/p>\n<p>Briefintroduction<\/p>\n<\/p>\n<table>\n<tbody>\n<tr align=\"left\">\n<td valign=\"center\">\n<\/td>\n<td valign=\"center\">\n<p>-ZLYJseriesreductiongearboxisatransmissionpart<\/p>\n<p>thatpossesseshighprecisionhardgearsurfaceand<\/p>\n<p>thrustblockdesignedforplasticscrewextruder.<\/p>\n<\/p>\n<p>-Thedesignofproductadaptsallkindsofnormspecified<\/p>\n<p>inZBJ19009-88\/itfeaturesthatgearandaxispartsare<\/p>\n<p>madeofhighstrengthalloysteel.<\/p>\n<\/p>\n<p>-Thegearisprocessesbycarburization,quenching<\/p>\n<p>andtoothgrindingprocess.<\/p>\n<\/p>\n<p>-Theprecisionofgearisgrade6specifiedinGB1009588.<\/p>\n<\/p>\n<p>-ThehardnessofgearsurfaceisHRC54~62.Atfrontend<\/p>\n<p>ofhollowinputaxisthereislargespecificationthrustbearing<\/p>\n<p>thatwillbearaxialthrustforcewhilethescrewis<\/p>\n<p>working.<\/p>\n<\/p>\n<p>-thecompletemachinefeaturescompact,highinbearing<\/p>\n<p>capacity,stableintransmission,lownoise,high<\/p>\n<p>efficiency,etc.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>ApplicationEnviroment:<\/p>\n<p>1.Theinputrotationofprimemovershallbe&le;1500rpm<\/p>\n<p>2.Theperipheralspeedofgeardriveshallbe&le;20m\/s<\/p>\n<p>3.Theworkingambienttemperatureshallbewithin-40~45&deg;C.Preheatthelubricationoiltoabove0&deg;C<\/p>\n<p>whentheambienttemperatureisbelow0&deg;C.Rotationisavailablebothforwardsandbackwards.<\/p>\n<p>However,thehighspeedshaftofsometypesofreducershasasinglewayoilpumpdirectingas<\/p>\n<p>defaultedtotheoutputshaftwhichrotatesclockwise.<\/p>\n<\/p>\n<p>FinishedProduct&amp;Application:<\/p>\n<p>ThisZLYJgearboxaremainlyusedinPlasticExtrudingMachine,likeEPS,PE&#8230;.<\/p>\n<\/p>\n<p>Processingequipment:<\/p>\n<p>WehaveNilescontourgeargrindingmachineimportedfromGermany,OKUMAhorizontalmachiningcenter<\/p>\n<p>importedfromJapan,gearinspectionandtestcenterandthree-coordinatesmeasuringmachine.<\/p>\n<\/p>\n<p><p>Embalaje y env\u00edo<\/p>\n<\/p>\n<p><strong> plastic extruder reducer ZLYJ twin screw extruder gearbox <\/strong><\/p>\n<p><strong>1. Embalaje industrial: tubo de pl\u00e1stico, cart\u00f3n y pal\u00e9s de madera.<\/strong><br \/><strong>2. Embalaje comercial: bolsa de pl\u00e1stico, caja de color, cart\u00f3n y pal\u00e9s de madera.<\/strong><br \/><strong>3. Seg\u00fan los requisitos del cliente. <\/strong><\/p>\n<p><strong>4. Env\u00edo: por mar, por aire, por DHL, Fedex, UPS, etc.<\/strong><\/p>\n<\/p>\n<\/p>\n<p><p>Informaci\u00f3n de la empresa<\/p>\n<\/p>\n<p>Como fabricante l\u00edder de motores industriales, reductores de velocidad, accionamientos, etc. en China, nuestra empresa siempre se ha adherido al concepto de \"innovaci\u00f3n tecnol\u00f3gica l\u00edder, logrando una calidad excelente\", los productos principales son: micromotores de engranajes, motores de engranajes de tama\u00f1o mediano, motores de regulaci\u00f3n de velocidad de freno, motores de par, motores de CC, motor de tornillo sin fin NMRV, motores de engranajes c\u00f3nicos helicoidales, reductor de tornillo sin fin de la serie WP RV, unidades de engranajes helicoidales de flanco de diente r\u00edgido, unidades de engranajes helicoidales de tornillo sin fin, unidades de engranajes helicoidales de eje paralelo, unidades de engranajes c\u00f3nicos en espiral, gato de tornillo sin fin SWL y JW, unidades de engranajes de flanco de diente r\u00edgido, unidades de engranajes planetarios, etc. productos de transmisi\u00f3n, que se utilizan ampliamente en varias l\u00edneas de producci\u00f3n industrial, como maquinaria de transporte, maquinaria alimentaria, maquinaria m\u00e9dica, maquinaria de impresi\u00f3n, maquinaria textil, maquinaria de embalaje, equipo de oficina, instrumentaci\u00f3n y otros campos, son los productos de soporte preferidos para equipos de automatizaci\u00f3n.<\/p>\n<\/p>\n<p><strong>\u00bfPOR QU\u00c9 ELEGIRNOS?<\/strong><br \/> -EXCELENTE SERVICIO, BAJOS COSTOS, ALTA ESTABILIDAD, CALIDAD AVANZADA, FUERZA LABORAL ESTABLE<br \/> -Poseemos alrededor de 300 juegos de equipos de procesamiento y equipos de prueba para garantizar la alta precisi\u00f3n y calidad, como la rectificadora de engranajes de precisi\u00f3n REISHAUER (Suiza), la fresadora de engranajes PFAUTER (Alemania), la fresadora de engranajes c\u00f3nicos Gleason, la m\u00e1quina de medici\u00f3n de tres coordenadas, etc.<\/p>\n<\/p>\n<p><p>Nuestros servicios<\/p>\n<\/p>\n<ul>\n<li>Entrega a tiempo<\/li>\n<li>Servicio 24 horas<\/li>\n<li>Calidad garantizada<\/li>\n<li>Visita a la f\u00e1brica de apoyo<\/li>\n<li>Soportes tecnol\u00f3gicos<\/li>\n<\/ul>\n<p>El equipo de Shanghai Taiqi agradece sinceramente su consulta y cooperaci\u00f3n.<\/p>\n<ul>\n<li>\u00a1Agradecemos mucho su visita!<\/li>\n<\/ul>\n<\/p>\n<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Quick Details Place of Origin: Zhejiang, China Brand Name: EPT Gearing Arrangement: Helical Output Torque: 350~100000Nm Input Speed: 1500,1000,750rpm Output Speed: 30-188r\/min Certificate: ISO9001, CE, CCC Mounting position: Horizontal (foot mounted) or Vertical (flange mounted) Color: According to customer&#039;s request Material: Steel or cast iron Gear material: Low carbon high alloy steel Gear accuracy: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[4],"class_list":["post-300","post","type-post","status-publish","format-standard","hentry","category-gearboxagricultural","tag-db"],"_links":{"self":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":1,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/300\/revisions"}],"predecessor-version":[{"id":2058,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/posts\/300\/revisions\/2058"}],"wp:attachment":[{"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/media?parent=300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/categories?post=300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearboxagricultural.com\/es\/wp-json\/wp\/v2\/tags?post=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}